{"id":413961,"date":"2025-10-10T12:08:43","date_gmt":"2025-10-10T11:08:43","guid":{"rendered":"https:\/\/whydonate.com\/?page_id=413961"},"modified":"2025-11-04T06:50:31","modified_gmt":"2025-11-04T05:50:31","slug":"awaryjna-zbiorka-pieniedzy","status":"publish","type":"page","link":"https:\/\/whydonate.com\/pl\/awaryjna-zbiorka-pieniedzy\/","title":{"rendered":"Emergency Fundraiser PL"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_14898769 height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"g-cols wpb_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Rozpocznij zbi\u00f3rk\u0119 funduszy w nag\u0142ych wypadkach&#8221; font_container=&#8221;tag:h1|font_size:40px|text_align:left|color:%23FFFFFF|line_height:47px&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;%7B%22default%22%3A%7B%22font-weight%22%3A%22700%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_5767c4fb has_text_color\"><div class=\"wpb_wrapper\"><p>Zbi\u00f3rki funduszy w nag\u0142ych wypadkach pomagaj\u0105 uzyska\u0107 natychmiastow\u0105 pomoc. Te zbi\u00f3rki funduszy s\u0105 przeznaczone dla os\u00f3b, kt\u00f3re borykaj\u0105 si\u0119 z nag\u0142ymi, krytycznymi problemami finansowymi. Trudne sytuacje mog\u0105 pojawi\u0107 si\u0119 w dowolnym momencie z powodu wielu nieprzewidzianych zdarze\u0144, takich jak kl\u0119ski \u017cywio\u0142owe, nag\u0142e wypadki medyczne lub nieoczekiwana utrata pracy. Zbi\u00f3rka funduszy w nag\u0142ych wypadkach zapewnia tymczasow\u0105 ulg\u0119, pomagaj\u0105c Tobie i Twoim bliskim ustabilizowa\u0107 sytuacj\u0119 finansow\u0105 i zaspokoi\u0107 pilne potrzeby.<\/p>\n<\/div><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_1 us_custom_b2cf3f66 has_text_color\" href=\"https:\/\/whydonate.com\/fundraising\/start\"><span class=\"w-btn-label\">Zarejestruj si\u0119 za Darmo<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"482\" height=\"376\" src=\"https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=9999\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=9999 482w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=300 300w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=38 38w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=256 256w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=250 250w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=128 128w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=450 450w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=64 64w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=100 100w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=350 350w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=108 108w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=54 54w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Emergency-Fundraiser.png\/w=13 13w\" sizes=\"auto, (max-width: 482px) 100vw, 482px\" title=\"\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\" class=\"attachment-large size-large wp-image-406348\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_eb849559\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Pomoc w nag\u0142ych wypadkach finansowych&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_eb849559\"><div class=\"wpb_wrapper\"><p>Kryzysy finansowe mog\u0105 nas spotka\u0107 w ka\u017cdej chwili. Zwolnienie z pracy, potrzeba funduszy z powodu katastrofy lub nieoczekiwane wydatki mog\u0105 przytrafi\u0107 si\u0119 ka\u017cdemu. Radz\u0105c sobie ze stresem psychicznym zwi\u0105zanym z tymi problemami, mo\u017cesz znale\u017a\u0107 ulg\u0119 finansow\u0105. W zale\u017cno\u015bci od kraju zamieszkania, w ka\u017cdej z tych sytuacji dost\u0119pne s\u0105 r\u00f3\u017cne rodzaje pomocy.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_5a2ef907 height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\" style=\"--additional-gap:20px;\"><div class=\"vc_col-sm-4 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_3243c04e\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_bc739ab2 has_text_color iconpos_top style_default color_primary align_left icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><svg width=\"79\" height=\"78\" viewBox=\"0 0 79 78\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" width=\"78\" height=\"78\" rx=\"39\" fill=\"#F4F4F4\"\/>\n<g clip-path=\"url(#clip0_18272_81960)\">\n<path d=\"M41.535 24.6629L20.5266 35.2211C21.9344 38.2109 23.3276 41.171 24.7368 44.1661L23.2955 44.8571L19.0933 35.9497C18.6467 36.1689 18.2216 36.3826 17.791 36.5883C17.2028 36.8706 16.7121 36.8101 16.3203 36.4176C15.9286 36.025 15.847 35.5155 16.1345 34.9388C18.8085 29.5446 21.4901 24.1517 24.1793 18.7601C24.4961 18.1229 24.8919 17.9186 25.6099 18.0315C28.8855 18.5477 32.1603 19.0706 35.4342 19.6003C38.2312 20.0484 41.0283 20.5001 43.8253 20.9553C44.4938 21.0642 44.8949 21.4151 44.9858 21.9595C45.0848 22.5295 44.8134 23.0014 44.193 23.3267C43.7986 23.5337 43.3988 23.73 42.9709 23.9478L53.8208 45.7645L52.3888 46.4945C48.7696 39.2151 45.161 31.9598 41.535 24.6629ZM18.152 34.4898L18.2282 34.5759L42.4575 22.3951C42.2022 22.3373 42.0658 22.2983 41.9227 22.2755C36.6255 21.4232 31.3256 20.5789 26.0297 19.7078C25.6112 19.6393 25.4508 19.7522 25.277 20.1111C22.9791 24.7606 20.6723 29.407 18.3566 34.0502C18.2871 34.1914 18.2216 34.3419 18.152 34.4898Z\" fill=\"#32BF55\"\/>\n<path d=\"M63.4999 47.7337V49.3388C62.8835 49.3388 62.2739 49.3523 61.6655 49.3267C61.5438 49.3267 61.4182 49.1789 61.3112 49.0807C59.7696 47.6558 57.6692 47.6477 56.1156 49.066C53.7678 51.2088 50.8638 51.2168 48.512 49.0942C46.8942 47.6316 44.8593 47.6423 43.2429 49.1211C40.9766 51.1926 38.0365 51.2007 35.7556 49.1426C34.0576 47.6128 32.0748 47.6235 30.3755 49.1735C28.1814 51.1738 25.2133 51.1805 22.9965 49.1896C21.2424 47.6141 19.3344 47.606 17.5763 49.156C17.4547 49.2607 17.3028 49.3234 17.1431 49.3348C16.6083 49.3563 16.0735 49.3442 15.5039 49.3442V47.7929C15.5173 47.7835 15.5467 47.7458 15.5694 47.7485C16.3516 47.844 16.9773 47.5321 17.6404 47.1275C19.6633 45.8907 22.1636 46.2375 24.0019 47.934C25.1464 48.9934 26.4513 49.3442 27.9194 48.8226C28.4161 48.632 28.8728 48.3493 29.2658 47.9892C31.6724 45.8517 34.5322 45.8504 36.9134 48.0201C38.447 49.4168 40.5234 49.4128 42.073 48.012C43.9448 46.3249 46.1468 45.9189 48.2045 46.946C48.762 47.2456 49.2791 47.6156 49.7434 48.047C51.2556 49.3846 53.3841 49.4571 54.824 48.047C56.9405 45.9714 60.0865 45.9324 62.0639 47.5886C62.2002 47.678 62.3598 47.7248 62.5225 47.723C62.8287 47.7472 63.1429 47.7337 63.4999 47.7337Z\" fill=\"#32BF55\"\/>\n<path d=\"M37.5653 37.7914C36.8193 37.7699 36.3313 37.5077 36.0478 36.9579C35.4502 35.7991 34.8606 34.6363 34.3097 33.4627C33.9327 32.6655 34.2549 31.7756 35.0437 31.3656C36.1517 30.7902 37.2681 30.2292 38.3929 29.6825C39.2419 29.2698 40.1311 29.5575 40.5656 30.395C41.1414 31.5081 41.6994 32.6284 42.2395 33.7558C42.6406 34.6054 42.3505 35.5034 41.5122 35.9362C40.4051 36.5156 39.2847 37.0681 38.163 37.6166C37.9703 37.6954 37.77 37.754 37.5653 37.7914ZM40.8129 34.4911C40.2407 33.3417 39.6925 32.2381 39.127 31.1035L35.755 32.7973C36.3232 33.9359 36.8781 35.049 37.4437 36.1849L40.8129 34.4911Z\" fill=\"#32BF55\"\/>\n<path d=\"M33.5985 38.3579C33.5865 39.1497 33.3097 39.6444 32.7428 39.9375C31.6037 40.5263 30.4619 41.111 29.304 41.6636C29.1202 41.7564 28.9198 41.8115 28.7146 41.8256C28.5093 41.8397 28.3034 41.8126 28.1087 41.7457C27.914 41.6789 27.7345 41.5737 27.5807 41.4364C27.4269 41.299 27.3019 41.1322 27.2129 40.9457C26.6273 39.8192 26.0613 38.6819 25.5149 37.5338C25.1138 36.6883 25.428 35.797 26.2677 35.3655C27.3533 34.808 28.4403 34.2627 29.5286 33.7295C30.4378 33.2845 31.3135 33.5655 31.7708 34.4581C32.327 35.5443 32.8658 36.6399 33.3979 37.7382C33.4824 37.9386 33.5495 38.1459 33.5985 38.3579ZM30.3175 35.1316L26.9442 36.8281L28.6328 40.213L32.0008 38.5192C31.4365 37.3792 30.887 36.2769 30.3175 35.1289V35.1316Z\" fill=\"#32BF55\"\/>\n<path d=\"M46.1474 42.1055C46.0912 43.1446 45.6941 43.8531 44.8999 44.2887C44.2141 44.6664 43.5108 45.0173 42.7995 45.3426C42.2503 45.606 41.621 45.6456 41.0433 45.4532C40.4657 45.2608 39.9845 44.8512 39.7003 44.3102C39.3246 43.6205 38.9756 42.9134 38.6534 42.1969C38.3969 41.6518 38.3575 41.0288 38.5432 40.4554C38.7289 39.882 39.1256 39.4018 39.6522 39.1131C40.3661 38.7098 41.0975 38.3455 41.8435 38.0148C42.8971 37.5456 44.1619 37.9045 44.7489 38.8886C45.2097 39.7041 45.627 40.5437 45.999 41.4038C46.0795 41.6299 46.1294 41.866 46.1474 42.1055ZM41.7112 44.0037C41.8875 43.9588 42.0607 43.9026 42.2299 43.8356C42.8276 43.5439 43.4266 43.2522 44.0135 42.9417C44.5483 42.6607 44.666 42.2789 44.4066 41.7318C44.1218 41.1282 43.8263 40.53 43.5148 39.9398C43.2474 39.4344 42.8717 39.3093 42.3463 39.558C41.7294 39.8484 41.1207 40.1545 40.5199 40.4762C40.0667 40.7168 39.9156 41.1161 40.1188 41.5718C40.425 42.244 40.7432 42.9027 41.1109 43.5358C41.2419 43.7482 41.5347 43.8665 41.7112 44.0037Z\" fill=\"#32BF55\"\/>\n<path d=\"M44.8275 54.9278L43.6978 56.0221C42.9878 55.3822 42.1254 55.0515 41.1574 55.4051C40.6831 55.6011 40.2519 55.8893 39.8886 56.2533C39.5037 56.6255 39.0488 56.9166 38.5505 57.1096C38.0522 57.3026 37.5206 57.3937 36.9869 57.3774C36.4531 57.3611 35.928 57.2378 35.4423 57.0148C34.9565 56.7918 34.52 56.4735 34.1582 56.0786L35.3268 55.0434C35.5748 55.2782 35.8669 55.4608 36.186 55.5806C36.5052 55.7004 36.8448 55.755 37.1852 55.7411C37.966 55.7089 38.5489 55.2989 39.0998 54.7719C39.8328 54.0575 40.8092 53.651 41.83 53.6352C42.8508 53.6195 43.8391 53.9957 44.5936 54.6872C44.6711 54.7531 44.7353 54.8284 44.8275 54.9278Z\" fill=\"#32BF55\"\/>\n<path d=\"M31.2931 56.5004L30.162 57.5356C29.6205 57.3272 29.0764 57.0193 28.4974 56.9172C27.6538 56.7693 26.9559 57.1618 26.3582 57.7654C24.7538 59.3705 22.41 59.4122 20.7214 57.8851C20.668 57.8333 20.6176 57.7785 20.5703 57.7211L21.6399 56.6658C22.0183 56.8567 22.4221 57.1444 22.87 57.2667C23.8594 57.5356 24.6843 57.1793 25.4103 56.4682C26.7821 55.1239 28.6833 54.8711 30.2877 55.788C30.503 55.9103 30.6982 56.0729 30.9027 56.2168L31.2931 56.5004Z\" fill=\"#32BF55\"\/>\n<path d=\"M57.6792 56.5207L56.516 57.6365C55.8849 57.0625 55.1015 56.6955 54.2257 56.9549C53.6763 57.1305 53.1735 57.4288 52.755 57.8274C51.0824 59.4042 48.621 59.3868 47.0059 57.7239L48.1156 56.7008C48.4659 56.8689 48.891 57.1552 49.3577 57.2762C50.3551 57.533 51.1586 57.1283 51.8806 56.4253C52.6102 55.6952 53.5905 55.2742 54.6195 55.2492C55.6486 55.2242 56.648 55.597 57.4118 56.2908C57.4787 56.358 57.5575 56.4199 57.6792 56.5207Z\" fill=\"#32BF55\"\/>\n<path d=\"M36.5976 44.1478L35.1777 44.867L34.314 43.1866L31.0423 44.824C30.807 44.3575 30.5784 43.9045 30.3203 43.3964C31.0115 43.0482 31.6734 42.7121 32.3352 42.3774C32.7817 42.1529 33.2203 41.9109 33.6722 41.7052C34.0165 41.5451 34.4072 41.5168 34.7708 41.6257C35.1343 41.7346 35.4459 41.9732 35.647 42.2967C35.9973 42.8869 36.2754 43.5133 36.5976 44.1478Z\" fill=\"#32BF55\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_18272_81960\">\n<rect width=\"48\" height=\"41\" fill=\"white\" transform=\"translate(15.5 18)\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:24px;\">Pomoc w przypadku katastrof<\/h4><div class=\"w-iconbox-text\"><p>Kl\u0119ski \u017cywio\u0142owe mog\u0105 nadej\u015b\u0107 w ka\u017cdej chwili. Nikt nie wie, kiedy dotknie go katastrofa. Ataki takie jak huragany, powodzie czy trz\u0119sienia ziemi mog\u0105 spowodowa\u0107 znaczne straty materialne i zachwia\u0107 Twoj\u0105 finansow\u0105 stabilno\u015bci\u0105.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_b31f667a\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_bc739ab2 has_text_color iconpos_top style_default color_primary align_left icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><svg width=\"79\" height=\"78\" viewBox=\"0 0 79 78\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" width=\"78\" height=\"78\" rx=\"39\" fill=\"#F4F4F4\"\/>\n<g clip-path=\"url(#clip0_18272_81976)\">\n<path d=\"M51.936 38.362C56.1705 38.6237 59.5975 42.5739 59.6662 47.1639C59.7338 51.6351 56.4541 55.9195 51.936 56.2335V58.0343C51.936 58.748 51.936 59.4533 51.936 60.1622C51.936 60.7867 51.74 60.9948 51.1718 60.9948H20.1093C19.5311 60.9948 19.334 60.7879 19.334 60.1789C19.334 48.3693 19.3377 36.5584 19.3451 24.7465C19.3566 24.4737 19.457 24.214 19.6286 24.0126C21.6903 21.7717 23.7645 19.5458 25.8513 17.335C26.0605 17.1338 26.3293 17.0183 26.61 17.0091C34.76 16.9925 42.9103 16.9881 51.061 16.996C51.7743 16.996 51.9349 17.1673 51.9349 17.9345C51.9349 24.5423 51.9349 31.1496 51.9349 37.7566L51.936 38.362ZM42.9277 47.1104H24.5831C24.4047 47.1104 24.1854 47.1604 24.0569 47.07C23.8764 46.9403 23.6538 46.706 23.6482 46.5109C23.6427 46.3159 23.8509 46.0637 24.0259 45.9245C24.1466 45.8294 24.3704 45.871 24.5476 45.871H42.4359C43.1282 45.871 43.1259 45.871 43.2954 45.1336C43.3355 44.9311 43.3899 44.7323 43.4582 44.5388C43.7396 43.8252 44.0331 43.1115 44.3443 42.361H24.5775C24.4264 42.3711 24.2748 42.3663 24.1245 42.3467C23.8033 42.2813 23.6028 42.0755 23.6205 41.7044C23.6382 41.3333 23.842 41.143 24.1743 41.1204C24.325 41.1097 24.4767 41.1144 24.6285 41.1144C31.3895 41.1144 38.1504 41.1168 44.9114 41.1216C45.0526 41.1269 45.1932 41.1007 45.3243 41.0446C45.4555 40.9885 45.5744 40.9037 45.6735 40.7957C46.945 39.4841 48.5859 38.6629 50.3388 38.4608C50.6988 38.418 50.7752 38.2728 50.7752 37.9065C50.7642 31.5192 50.7612 25.1322 50.7664 18.7457C50.7664 18.5899 50.752 18.4341 50.7431 18.2699H26.9589V18.7659C26.9589 20.6286 26.9589 22.4921 26.9589 24.3563C26.9589 25.0272 26.8005 25.1949 26.1747 25.1961C24.4394 25.1961 22.7041 25.1961 20.9688 25.1961H20.5258V59.7281H50.742V56.2109C50.5803 56.1835 50.4452 56.1562 50.31 56.1371C47.8555 55.7803 45.9183 54.5005 44.5072 52.325C44.2856 51.9753 44.0641 51.8635 43.6742 51.8635C37.3127 51.8777 30.9512 51.8809 24.5897 51.873C24.4383 51.8797 24.2867 51.8769 24.1356 51.8646C23.8199 51.823 23.636 51.6268 23.6205 51.2818C23.605 50.9369 23.7856 50.724 24.0857 50.6478C24.2355 50.6225 24.3875 50.6158 24.5388 50.6276H43.5247C43.3253 49.4548 43.1348 48.3237 42.9277 47.1104ZM51.3457 54.9667C52.7586 54.9672 54.1399 54.5178 55.3149 53.6753C56.49 52.8327 57.406 51.635 57.9472 50.2335C58.4884 48.8319 58.6305 47.2895 58.3554 45.8013C58.0804 44.313 57.4006 42.9458 56.402 41.8724C55.4034 40.7991 54.1308 40.0678 52.7452 39.771C51.3596 39.4743 49.9231 39.6254 48.6175 40.2053C47.3118 40.7851 46.1956 41.7677 45.41 43.0288C44.6243 44.2899 44.2045 45.7728 44.2037 47.29C44.2034 49.3253 44.9558 51.2773 46.2956 52.7169C47.6353 54.1565 49.4526 54.9658 51.3479 54.9667H51.3457ZM25.7738 19.3297L21.4972 23.9222H25.7738V19.3297Z\" fill=\"#32BF55\"\/>\n<path d=\"M44.4495 27.4513C44.3731 27.8569 44.2369 28.2625 44.228 28.6705C44.2047 30.5914 44.2202 32.5136 44.2169 34.4345C44.2136 36.3555 43.1093 37.5545 41.3083 37.558C40.2062 37.558 39.1052 37.558 38.0042 37.558C36.3051 37.5509 35.1831 36.3555 35.1653 34.5356C35.1576 33.703 35.1565 32.8799 35.1653 32.0521C35.1653 31.8059 35.0989 31.6952 34.8685 31.6167C34.2039 31.3895 33.6501 30.9459 33.3477 30.2691C32.5934 28.5967 31.8447 26.9196 31.1668 25.2116C30.7481 24.1553 31.4769 23.1086 32.5591 23.0373C32.8215 23.0129 33.078 22.9392 33.3167 22.8196C33.5032 22.7216 33.715 22.6942 33.9179 22.7417C34.1207 22.7892 34.3027 22.9088 34.4343 23.0813C34.5627 23.2573 34.6298 23.476 34.6239 23.6995C34.618 23.923 34.5396 24.1372 34.4022 24.3052C34.2634 24.4712 34.0762 24.5815 33.8712 24.6181C33.6663 24.6546 33.4559 24.6152 33.2746 24.5062C33.0654 24.3881 32.835 24.3195 32.599 24.3052C32.2921 24.2993 32.1282 24.5134 32.2667 24.8393C32.9601 26.4617 33.6124 28.1067 34.3867 29.6827C34.5172 29.9475 34.7128 30.1688 34.9521 30.3228C35.1914 30.4768 35.4655 30.5574 35.7444 30.5561C36.0234 30.5547 36.2968 30.4714 36.5348 30.3152C36.7729 30.1589 36.9665 29.9356 37.0948 29.6696C37.8691 28.1031 38.517 26.4736 39.1982 24.8619C39.2503 24.7429 39.1861 24.4206 39.1273 24.4051C38.8834 24.3538 38.6342 24.3382 38.3863 24.3587C38.3177 24.3587 38.2567 24.4646 38.1859 24.5074C38.0045 24.6174 37.7931 24.6557 37.5882 24.6158C37.3833 24.5759 37.1979 24.4602 37.0641 24.2889C36.9304 24.1175 36.8566 23.9013 36.8558 23.6777C36.8549 23.454 36.9269 23.2372 37.0594 23.0646C37.1949 22.8958 37.3792 22.7807 37.5828 22.7376C37.7863 22.6945 37.9975 22.7259 38.1825 22.8267C38.4079 22.9438 38.6518 23.0144 38.9014 23.0349C40.0279 23.1027 40.7367 24.166 40.2948 25.2758C39.6413 26.9137 38.9247 28.5289 38.208 30.1383C38.0523 30.495 37.8275 30.8119 37.5486 31.0679C37.2698 31.3239 36.9432 31.513 36.5909 31.6227C36.3693 31.6976 36.3261 31.8225 36.3273 32.0402C36.335 32.8966 36.3217 33.7542 36.3339 34.6118C36.3461 35.599 36.9209 36.277 37.8392 36.302C39.0775 36.3376 40.3181 36.34 41.5564 36.302C42.4879 36.2734 43.0561 35.5823 43.0583 34.5618C43.0583 32.6408 43.0716 30.7187 43.0583 28.7966C43.0495 27.7463 43.3253 26.8518 44.1073 26.1726C44.1945 26.0836 44.2537 25.9676 44.2767 25.8408C44.5127 24.7049 45.2736 23.9948 46.2849 23.9734C46.7475 23.9611 47.2007 24.1159 47.5717 24.4129C47.9428 24.7099 48.2104 25.132 48.3316 25.6117C48.4528 26.0913 48.4207 26.6008 48.2404 27.0585C48.0601 27.5162 47.7421 27.8958 47.3371 28.1364C46.4588 28.6645 45.4541 28.4611 44.722 27.6083L44.6112 27.4798L44.4495 27.4513ZM45.4187 26.1714C45.4159 26.3003 45.4368 26.4285 45.4801 26.5487C45.5235 26.6689 45.5885 26.7788 45.6714 26.872C45.7543 26.9652 45.8535 27.04 45.9633 27.0921C46.0731 27.1441 46.1914 27.1724 46.3115 27.1753C46.5537 27.1714 46.7851 27.0669 46.9571 26.8837C47.1291 26.7005 47.2284 26.4529 47.2341 26.1929C47.233 25.9395 47.1397 25.6967 46.9741 25.5162C46.8086 25.3358 46.5839 25.232 46.348 25.227C46.2286 25.2208 46.1093 25.2405 45.9972 25.2851C45.8851 25.3296 45.7825 25.3981 45.6957 25.4863C45.6089 25.5746 45.5396 25.6807 45.492 25.7985C45.4444 25.9162 45.4195 26.0431 45.4187 26.1714Z\" fill=\"#32BF55\"\/>\n<path d=\"M25.0343 30.8954C25.0343 30.3637 25.0288 29.8499 25.0343 29.336C25.0421 28.8531 25.2448 28.6224 25.6889 28.6224C26.5831 28.6129 27.4777 28.6129 28.3727 28.6224C28.8158 28.6224 29.0118 28.846 29.0207 29.336C29.0295 29.8487 29.0207 30.3637 29.0207 30.9311C29.5258 30.9311 29.9887 30.9311 30.4517 30.9311C30.9779 30.9311 31.1817 31.1416 31.1872 31.7018C31.1961 32.6193 31.1961 33.5356 31.1872 34.4507C31.1872 35.0204 30.9923 35.2178 30.4562 35.2286C29.9921 35.2369 29.5291 35.2286 29.0162 35.2286C29.0162 35.79 29.0218 36.2895 29.0162 36.7879C29.0085 37.3279 28.8147 37.5444 28.3162 37.5492C27.4633 37.5587 26.6105 37.5575 25.7565 37.5492C25.2304 37.5492 25.0332 37.3291 25.0288 36.7713C25.0288 36.2729 25.0288 35.7745 25.0288 35.225C24.5314 35.225 24.0806 35.225 23.6309 35.225C23.045 35.2155 22.8733 35.0263 22.8711 34.3924C22.8711 33.5201 22.8711 32.6479 22.8711 31.7756C22.8711 31.1083 23.0505 30.9251 23.6907 30.9228C24.0895 30.9228 24.4882 30.9228 24.887 30.9168C24.9365 30.9136 24.9858 30.9064 25.0343 30.8954ZM24.0529 33.988C24.5469 33.988 25 33.9808 25.4519 33.988C25.999 33.9975 26.1885 34.2092 26.1929 34.7992C26.1929 35.294 26.1929 35.7888 26.1929 36.2848H27.8632C27.8632 35.7793 27.8632 35.3082 27.8632 34.8372C27.8632 34.1949 28.0537 33.9939 28.6552 33.9868C29.0982 33.9868 29.5501 33.9868 29.9932 33.9868V32.2264C29.9578 32.2091 29.9206 32.1963 29.8824 32.1883L28.6452 32.1812C28.0493 32.1812 27.8698 31.9802 27.8621 31.3296C27.8621 30.8538 27.8621 30.3697 27.8621 29.9022H26.1929C26.1929 30.4339 26.1929 30.9347 26.1929 31.4354C26.1862 31.9647 25.9835 32.1776 25.484 32.1824C25.0088 32.1824 24.5337 32.1824 24.054 32.1824L24.0529 33.988Z\" fill=\"#32BF55\"\/>\n<path d=\"M31.718 55.3993H38.8999C39.024 55.3993 39.148 55.3993 39.271 55.4064C39.611 55.4409 39.8027 55.6598 39.8115 56.013C39.8204 56.3663 39.6277 56.5614 39.3219 56.6292C39.1858 56.6487 39.0481 56.6539 38.911 56.6446C34.1113 56.6446 29.3115 56.6446 24.5118 56.6446C24.361 56.6564 24.2093 56.6464 24.061 56.6149C23.923 56.5879 23.8004 56.5039 23.7195 56.3809C23.6385 56.258 23.6056 56.1058 23.6279 55.9571C23.6317 55.8147 23.6855 55.6792 23.7786 55.5777C23.8717 55.4761 23.9971 55.4162 24.1297 55.41C24.2666 55.3969 24.4043 55.3933 24.5417 55.3993H31.718Z\" fill=\"#32BF55\"\/>\n<path d=\"M51.9533 51.5525C51.9645 51.7267 51.9645 51.9016 51.9533 52.0758C51.9057 52.4327 51.7063 52.6503 51.3718 52.6432C51.0373 52.6361 50.8047 52.4243 50.818 52.0616C50.8324 51.6678 50.6806 51.5263 50.3561 51.3752C49.9884 51.2052 49.6627 50.8995 49.3592 50.6116C49.11 50.3737 49.1167 50.0478 49.3426 49.779C49.5686 49.5102 49.8444 49.4924 50.118 49.7076C50.2287 49.7933 50.3162 49.9289 50.437 49.986C50.7327 50.1251 51.0362 50.3131 51.3463 50.3345C52.0652 50.3832 52.6533 49.8242 52.6644 49.1724C52.6755 48.5206 52.1516 47.9948 51.425 47.9651C50.7249 47.9354 50.0958 47.7272 49.5796 47.211C48.3757 45.993 48.7722 43.9424 50.3616 43.2858C50.6828 43.1538 50.7726 43.0051 50.7548 42.659C50.7338 42.2284 50.9919 41.9453 51.3297 41.9453C51.6675 41.9453 51.9112 42.2201 51.8979 42.659C51.8868 43.0289 52.0209 43.1704 52.341 43.3132C52.7397 43.5045 53.1076 43.7626 53.4309 44.078C53.4937 44.1319 53.5445 44.2002 53.5796 44.2778C53.6148 44.3554 53.6334 44.4405 53.6342 44.5268C53.6349 44.6131 53.6177 44.6985 53.5839 44.7769C53.5501 44.8552 53.5005 44.9244 53.4386 44.9796C53.2049 45.2175 52.8638 45.1901 52.5913 44.9177C52.0707 44.3979 51.4837 44.1577 50.7803 44.442C50.5708 44.5182 50.3882 44.6619 50.2572 44.8534C50.1262 45.0448 50.0533 45.2749 50.0482 45.5125C50.0537 45.7509 50.1284 45.9815 50.2619 46.1721C50.3953 46.3627 50.5808 46.5038 50.7925 46.5758C50.9996 46.653 51.216 46.6975 51.4349 46.7079C52.6533 46.7816 53.6413 47.6309 53.8019 48.7692C53.9736 49.986 53.3655 50.9744 52.1405 51.474C52.0818 51.4954 52.0319 51.518 51.9533 51.5525Z\" fill=\"#32BF55\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_18272_81976\">\n<rect width=\"40.3333\" height=\"44\" fill=\"white\" transform=\"translate(19.334 17)\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:24px;\">Nieoczekiwane wydatki medyczne<\/h4><div class=\"w-iconbox-text\"><p>Rachunki zwi\u0105zane z opiek\u0105 zdrowotn\u0105 to jeden z g\u0142\u00f3wnych powod\u00f3w, dla kt\u00f3rych wielu naszych fundator\u00f3w popada w k\u0142opoty finansowe. Wysokie rachunki medyczne wynikaj\u0105ce z nieoczekiwanej choroby lub wypadku mog\u0105 szybko uszczupli\u0107 oszcz\u0119dno\u015bci i doprowadzi\u0107 do kryzysu finansowego.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_b31f667a\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_bc739ab2 has_text_color iconpos_top style_default color_primary align_left icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><svg width=\"79\" height=\"78\" viewBox=\"0 0 79 78\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" width=\"78\" height=\"78\" rx=\"39\" fill=\"#F4F4F4\"\/>\n<path d=\"M15.4056 26.461C15.8448 25.0834 16.782 24.5849 18.1359 24.6098C20.726 24.6582 23.3187 24.6831 25.9076 24.6098C27.7244 24.5548 28.9106 25.451 28.768 27.6371C28.7254 28.3004 28.6816 28.9454 28.2574 29.4687C28.9657 30.9627 28.9657 32.3194 28.2574 33.6093C28.9694 34.8705 28.9657 36.4875 28.2712 37.6453C28.9056 38.9876 29.012 40.3024 28.3275 41.6368C28.2912 41.7074 28.2662 41.8409 28.3037 41.8867C28.3359 41.9266 28.3759 41.959 28.421 41.9816C28.4661 42.0041 28.5153 42.0164 28.5653 42.0175C29.3348 41.905 30.0993 41.7061 30.8701 41.6708C31.6409 41.6355 32.3866 41.765 33.1724 41.8239C32.5193 40.4593 32.4842 39.0857 33.1862 37.6374C32.5118 36.8172 32.6857 35.7614 32.7445 34.7501C32.8033 33.7388 33.7455 32.8414 34.7465 32.8348C37.833 32.8148 40.9236 32.8148 44.0185 32.8348C44.9381 32.8348 45.7289 33.5583 45.9804 34.5146C46.2219 35.4304 46.0355 36.8577 45.5825 37.6414C46.2019 38.9797 46.307 40.2945 45.6426 41.6315C45.5951 41.7257 45.6426 41.8932 45.6914 42.0096C45.956 42.5734 46.0935 43.193 46.0935 43.8209C46.0935 44.4489 45.956 45.0685 45.6914 45.6322C45.6351 45.7801 45.6351 45.9448 45.6914 46.0927C45.9562 46.6561 46.0939 47.2756 46.0939 47.9033C46.0939 48.5311 45.9562 49.1505 45.6914 49.714C45.6414 49.8291 45.5875 50.0018 45.6326 50.0934C46.3008 51.4304 46.1994 52.7439 45.5988 54.0508C46.2495 55.4114 46.252 56.772 45.5713 58.1836C46.2507 59.068 46.1031 60.1565 45.9867 61.1926C45.8703 62.2288 44.9406 62.9876 43.9371 62.9915C40.8932 63.0037 37.8484 63.0037 34.8028 62.9915C34.2578 62.9818 33.7371 62.7536 33.3482 62.3541C32.9594 61.9546 32.7321 61.4143 32.7132 60.8446C32.7057 60.6523 32.7132 60.46 32.7132 60.3488L28.7717 60.1827C28.7592 60.3841 28.7529 60.6903 28.7192 60.9925C28.6682 61.5345 28.4281 62.0378 28.0448 62.4066C27.6614 62.7753 27.1616 62.9835 26.6408 62.9915C23.596 63.0072 20.5513 63.0072 17.5065 62.9915C16.6131 62.9915 15.9825 62.4904 15.5883 61.6597C15.5208 61.5184 15.4632 61.3732 15.3944 61.2306V59.1688C15.552 58.8221 15.711 58.4754 15.8711 58.1221C15.7185 57.7964 15.5558 57.4536 15.3944 57.1096V55.0556L15.8699 54.0443L15.3944 52.9977V50.9424C15.5345 50.6611 15.6847 50.3851 15.8111 50.096C15.8468 49.9996 15.8468 49.8928 15.8111 49.7964C15.6859 49.4876 15.537 49.1894 15.3969 48.8806V46.9274C15.537 46.6239 15.6847 46.3256 15.8111 46.0116C15.8468 45.9152 15.8468 45.8084 15.8111 45.712C15.6859 45.4242 15.5358 45.1481 15.3944 44.8669V42.8142L15.8699 41.7676C15.7185 41.4445 15.5558 41.1017 15.3944 40.7576V38.701L15.8711 37.6858L15.3944 36.6392V34.5879C15.5345 34.3066 15.6847 34.0306 15.8098 33.7414C15.8461 33.6452 15.8461 33.5381 15.8098 33.4418C15.6847 33.1331 15.5358 32.8348 15.3956 32.5261V30.5741C15.5345 30.2719 15.6822 29.9723 15.8085 29.6584C15.8441 29.562 15.8441 29.4552 15.8085 29.3588C15.6834 29.071 15.532 28.7949 15.3906 28.5136L15.4056 26.461ZM31.0565 43.2067C29.5845 43.2106 28.1467 43.6706 26.9246 44.5286C25.7026 45.3867 24.7513 46.6042 24.1909 48.0274C23.6305 49.4505 23.4862 51.0154 23.7762 52.5243C24.0661 54.0332 24.7774 55.4184 25.8201 56.5047C26.8629 57.5911 28.1902 58.3299 29.6343 58.6277C31.0785 58.9256 32.5747 58.7692 33.9339 58.1783C35.2931 57.5873 36.4542 56.5884 37.2706 55.3077C38.0869 54.027 38.5218 52.522 38.5204 50.983C38.521 49.9593 38.3282 48.9455 37.9531 47.9999C37.5779 47.0544 37.0277 46.1956 36.3342 45.473C35.6406 44.7504 34.8173 44.1782 33.9116 43.7893C33.0059 43.4004 32.0356 43.2024 31.0565 43.2067ZM22.0586 28.7164H25.895C27.2126 28.7164 27.2639 28.6615 27.2589 27.2865C27.2589 26.3877 27.0712 26.1915 26.2154 26.1915H18.4087C16.9259 26.1915 16.8959 26.2216 16.9072 27.781C16.9072 28.4835 17.1311 28.7151 17.8043 28.7151C19.2216 28.7177 20.6397 28.7182 22.0586 28.7164ZM22.1049 30.2863H18.3148C16.9472 30.2863 16.9022 30.3347 16.9047 31.7699C16.9047 32.619 17.1024 32.8165 17.9357 32.8165H25.7486C27.2327 32.8165 27.3027 32.7406 27.2589 31.1838C27.2402 30.5297 27.0087 30.285 26.3618 30.2837C24.9428 30.2798 23.5239 30.2837 22.1049 30.2837V30.2863ZM22.0674 34.3877H18.2836C16.9347 34.3877 16.9072 34.4165 16.9072 35.8504C16.9072 36.7073 17.0999 36.9074 17.9307 36.9087H25.7424C27.2364 36.9087 27.3027 36.8381 27.2614 35.2865C27.2439 34.6114 27.0287 34.3903 26.373 34.389C24.9366 34.3847 23.5014 34.3834 22.0674 34.3851V34.3877ZM39.41 34.3877H35.6224C34.2273 34.3877 34.211 34.4047 34.2147 35.8582C34.2147 36.7256 34.3924 36.9048 35.2408 36.9048H43.05C44.5515 36.9048 44.5653 36.8917 44.5515 35.3231C44.5452 34.6075 44.3388 34.3864 43.6656 34.3851C42.2467 34.3834 40.8281 34.3834 39.41 34.3851V34.3877ZM22.0662 61.4281C23.2987 61.4281 24.5324 61.398 25.7637 61.436C27.3653 61.4857 27.2652 61.2018 27.2527 59.7418C27.2527 59.624 27.2076 59.4343 27.1275 59.4003C26.7234 59.2145 26.3055 58.9359 25.8875 58.9293C23.4075 58.8849 20.9262 58.9071 18.4462 58.9071C16.8997 58.9071 16.8734 58.9346 16.8997 60.5463C16.9097 61.1822 17.1387 61.4255 17.7555 61.4268C19.1957 61.4307 20.6309 61.4281 22.0662 61.4281ZM39.36 61.4281H43.1513C44.539 61.4281 44.5565 61.4098 44.5515 59.9459C44.5515 59.102 44.3663 58.9084 43.5605 58.9084C41.4533 58.9084 39.3462 58.928 37.2403 58.8966C36.3844 58.8835 35.6024 58.983 34.8266 59.433C34.3611 59.7038 34.1659 59.938 34.201 60.4862C34.2523 61.2175 34.4212 61.4268 35.1444 61.4281C36.55 61.4299 37.9552 61.4299 39.36 61.4281ZM22.0511 38.4734H18.2635C16.9409 38.4734 16.9034 38.5127 16.9047 39.9033C16.9047 40.8034 17.0773 40.9853 17.9457 40.9853H25.8012C27.2339 40.9853 27.289 40.9264 27.2589 39.4049C27.2452 38.6906 27.0437 38.476 26.3543 38.4734C24.9153 38.4695 23.4851 38.4734 22.0511 38.4734ZM39.41 38.4734H35.6762C34.2185 38.4734 34.2135 38.4734 34.221 39.9923C34.221 40.7773 34.4062 40.9774 35.1544 40.9774H43.1013C44.5665 40.9774 44.5665 40.9774 44.5578 39.4625C44.5578 38.6775 44.3688 38.4747 43.6243 38.4721C42.2154 38.4708 40.8127 38.4734 39.41 38.4734ZM26.7697 42.6101C26.6954 42.5832 26.6179 42.5673 26.5394 42.563C23.5789 42.563 20.6176 42.563 17.6554 42.563C17.1549 42.563 16.9209 42.8391 16.9047 43.3584C16.8959 43.6515 16.9047 43.9459 16.9047 44.2389C16.9159 44.8158 17.1549 45.0736 17.7055 45.0762C19.7476 45.0814 21.7913 45.0814 23.8367 45.0762C23.9724 45.0872 24.108 45.0523 24.2233 44.9768C25.0805 44.1866 25.9301 43.3872 26.7697 42.6101ZM35.1432 42.5499C36.1652 43.2031 37.0923 44.0062 37.896 44.9349C37.9861 45.0422 38.2 45.0657 38.3565 45.0736C39.9305 45.0827 41.5059 45.0736 43.08 45.0736C44.5678 45.0736 44.5678 45.0736 44.5565 43.5246C44.5565 42.7645 44.3438 42.546 43.5993 42.5447C41.9476 42.5447 40.2951 42.5447 38.6417 42.5447L35.1432 42.5499ZM24.3697 57.3149C23.9305 56.5928 23.4939 55.9099 23.0947 55.1995C22.9508 54.9378 22.8119 54.8306 22.5229 54.8332C21.1352 54.8489 19.7476 54.8397 18.3599 54.8397C16.8984 54.8397 16.8972 54.8397 16.9047 56.3625C16.9047 57.1305 17.1086 57.3437 17.8519 57.345C19.8948 57.345 21.9385 57.345 23.9831 57.345C24.112 57.3385 24.2434 57.3189 24.3697 57.3097V57.3149ZM37.7834 57.3058C37.7721 57.2966 37.7946 57.3306 37.8172 57.3306C39.8417 57.3306 41.8675 57.3437 43.8921 57.3306C44.3188 57.3306 44.5377 57.0481 44.5477 56.6033C44.5552 56.2775 44.5577 55.9491 44.5477 55.626C44.5327 55.1027 44.3112 54.841 43.797 54.841C42.3643 54.8279 40.9303 54.8319 39.4964 54.841C39.4312 54.8415 39.3668 54.8562 39.3073 54.8841C39.2479 54.912 39.1946 54.9526 39.151 55.0033C38.688 55.7542 38.2413 56.5274 37.7834 57.3006V57.3058ZM23.0797 46.6409H18.43C16.9072 46.6409 16.8884 46.6657 16.9072 48.2461C16.9072 48.9329 17.1437 49.1697 17.8206 49.171C19.177 49.171 20.5325 49.171 21.8872 49.171C22.0236 49.171 22.16 49.154 22.2426 49.1488C22.5229 48.301 22.7881 47.5069 23.0797 46.6409ZM22.3289 53.2633C22.2426 52.3972 22.1638 51.5952 22.0787 50.7462C20.5596 50.7462 19.0368 50.7344 17.514 50.7553C17.1387 50.7553 16.9322 51.0497 16.9109 51.4396C16.8934 51.781 16.8984 52.1238 16.9109 52.4665C16.9247 52.9611 17.1524 53.2515 17.6204 53.2515C19.1732 53.275 20.731 53.2633 22.3277 53.2633H22.3289ZM39.0759 46.6409C39.3262 47.4363 39.5489 48.1938 39.7992 48.9421C39.8273 49.0002 39.8684 49.0505 39.9189 49.0887C39.9693 49.127 40.0278 49.152 40.0895 49.1619C41.3532 49.1763 42.617 49.1841 43.8808 49.1619C44.2925 49.1553 44.5377 48.8871 44.549 48.4371C44.5565 48.1114 44.559 47.783 44.549 47.4585C44.5365 46.9091 44.2987 46.65 43.7694 46.6461C42.6934 46.6356 41.616 46.6461 40.5387 46.6461L39.0759 46.6409ZM39.7992 53.2554C41.1693 53.2554 42.5244 53.2672 43.8808 53.2476C44.2937 53.2476 44.539 52.9755 44.549 52.5241C44.5565 52.1983 44.559 51.87 44.549 51.5455C44.5352 50.9921 44.2987 50.7462 43.7682 50.7423C42.7234 50.7344 41.6773 50.7423 40.6325 50.7423H40.0707C39.9781 51.6018 39.8918 52.3933 39.7979 53.2554H39.7992Z\" fill=\"#32BF55\"\/>\n<path d=\"M50.5238 58.1511C49.7943 56.8742 49.793 55.2729 50.4938 54.0746C49.7955 52.6956 49.8056 51.3377 50.4712 49.9444C49.798 48.6047 49.7918 47.2297 50.4938 45.8247C49.8181 44.8644 49.9169 43.7419 50.1096 42.6535C50.2898 41.6409 51.182 40.9972 52.2693 40.9854C54.1575 40.9658 56.0456 40.9789 57.9351 40.9789C58.9486 40.9789 59.9634 40.971 60.9782 40.9789C62.4797 40.992 63.3556 41.9274 63.3618 43.492C63.3618 44.277 63.4219 45.062 62.9276 45.7462C62.8826 45.809 62.9439 45.983 62.9914 46.0876C63.5458 47.2938 63.5395 48.4948 63.004 49.7063C62.9408 49.8372 62.9287 49.9887 62.9702 50.1288C63.262 50.7323 63.4073 51.4016 63.3931 52.0777C63.3789 52.7537 63.2057 53.4157 62.8888 54.0052C63.572 55.4024 63.572 56.763 62.8788 58.1812C63.5458 59.0224 63.4181 60.0768 63.3155 61.0868C63.2029 62.2001 62.282 62.9851 61.2059 62.989C58.1937 62.9995 55.1814 62.9995 52.1692 62.989C51.6314 62.9987 51.1107 62.7918 50.7147 62.4112C50.3188 62.0305 50.0779 61.5053 50.042 60.9442C49.9732 59.9774 49.8531 58.9753 50.5238 58.1511ZM56.655 45.0685H60.4902C61.8115 45.0685 61.8578 45.0188 61.8565 43.6425C61.8565 42.7267 61.6739 42.5396 60.7779 42.5396H53.0176C51.5361 42.5396 51.4635 42.6168 51.5073 44.175C51.5261 44.8435 51.745 45.0672 52.4032 45.0685C53.8196 45.0763 55.2411 45.0737 56.66 45.075L56.655 45.0685ZM56.7026 50.7333H52.9187C51.5423 50.7333 51.4985 50.7751 51.5073 52.2103C51.5073 53.0528 51.7 53.2569 52.5083 53.2569H60.3663C61.8603 53.2569 61.8816 53.2333 61.8678 51.6713C61.8678 50.9701 61.6426 50.7372 60.9694 50.7359C59.5442 50.7372 58.1265 50.7398 56.7076 50.7398L56.7026 50.7333ZM56.6575 61.4217H60.4514C61.839 61.4217 61.8653 61.3943 61.8616 59.946C61.8616 59.114 61.6626 58.8994 60.8718 58.8994C58.2533 58.8994 55.6344 58.8994 53.0151 58.8994C51.5273 58.8994 51.4798 58.9491 51.5073 60.4837C51.5198 61.1967 51.73 61.4191 52.4069 61.4191C53.8259 61.427 55.2444 61.43 56.6625 61.4283L56.6575 61.4217ZM56.6575 49.166H60.4514C61.814 49.166 61.8603 49.1176 61.8565 47.6759C61.8565 46.8451 61.6576 46.6358 60.8655 46.6293H53.0101C51.5261 46.6293 51.4798 46.6777 51.5085 48.2162C51.521 48.9174 51.7463 49.1581 52.4107 49.1594C53.8284 49.1751 55.2473 49.1725 56.6663 49.1725L56.6575 49.166ZM56.6963 54.8203H52.9175C51.5411 54.8203 51.4985 54.8634 51.5073 56.3025C51.5073 57.1463 51.69 57.3334 52.5083 57.3334C55.1435 57.3334 57.7778 57.3334 60.4113 57.3334C61.8565 57.3334 61.8716 57.319 61.8641 55.8041C61.8641 55.0387 61.6576 54.8242 60.9156 54.8216C59.5104 54.8242 58.1077 54.8268 56.7051 54.8268L56.6963 54.8203Z\" fill=\"#32BF55\"\/>\n<path d=\"M54.4354 32.0276C54.1852 31.8209 53.9349 31.6116 53.6847 31.4075C50.0293 28.4569 46.376 25.5055 42.7248 22.5532C42.4683 22.3465 42.2768 22.3138 41.974 22.4695C39.5503 23.7372 37.1116 24.9748 34.6904 26.249C34.1636 26.5264 33.777 26.4636 33.3403 26.0632C29.9143 22.9234 26.4812 19.7928 23.0411 16.6713C22.4605 16.148 22.3454 15.6744 22.6882 15.2688C23.0311 14.8632 23.469 14.9156 24.0646 15.4559C27.3363 18.4326 30.605 21.4124 33.8708 24.3952C34.1298 24.6333 34.315 24.6399 34.6028 24.4907C37.014 23.2322 39.4377 22.005 41.8464 20.7334C42.3469 20.4717 42.7286 20.5136 43.169 20.8721C47.123 24.0825 51.0854 27.2834 55.0561 30.4747C55.1812 30.5728 55.3063 30.6657 55.5266 30.841C55.4252 30.2771 55.3439 29.8284 55.2613 29.3797C55.1537 28.7988 55.3752 28.3867 55.8481 28.2925C56.3211 28.1983 56.6665 28.4744 56.7766 29.0278C57.0106 30.2052 57.2383 31.3892 57.451 32.5744C57.5924 33.3699 57.3046 33.7283 56.5463 33.7309C55.406 33.7309 54.2669 33.7288 53.1291 33.7244C52.5348 33.7244 52.2119 33.4392 52.2069 32.9395C52.2019 32.4397 52.5235 32.1414 53.1129 32.1349C53.542 32.1349 53.9725 32.1349 54.4017 32.1349L54.4354 32.0276Z\" fill=\"#32BF55\"\/>\n<path d=\"M32.9509 53.3248C32.8846 52.6772 32.6443 52.2926 32.2001 52.1252C31.6621 51.9211 31.094 51.8033 30.5434 51.6293C30.1674 51.5269 29.8006 51.3903 29.4473 51.2211C27.5704 50.2308 27.4453 47.8014 29.1971 46.5808C29.4009 46.4305 29.626 46.3145 29.864 46.2367C30.1968 46.1412 30.322 45.975 30.3245 45.5982C30.3245 44.9441 30.9501 44.5582 31.4268 44.9062C31.5269 44.9882 31.61 45.0905 31.6713 45.2069C31.7326 45.3234 31.7707 45.4516 31.7835 45.5839C31.7947 45.9659 31.9286 46.1072 32.2589 46.2157C32.67 46.3511 33.0483 46.5774 33.3683 46.8792C33.6883 47.181 33.9424 47.5513 34.1133 47.9649C34.326 48.4437 34.1934 48.8807 33.7917 49.0861C33.3901 49.2915 33.0335 49.1253 32.782 48.6713C32.2014 47.6247 31.104 47.2571 30.1543 47.7987C29.7264 48.0408 29.4473 48.3966 29.4661 48.9291C29.4849 49.4341 29.7977 49.7376 30.2169 49.8906C30.636 50.0437 31.0928 50.117 31.5207 50.2583C32.0537 50.4336 32.613 50.5696 33.0923 50.8522C34.0445 51.4121 34.5 52.324 34.4086 53.4687C34.3223 54.5559 33.6804 55.2336 32.7507 55.6404C32.55 55.7317 32.3402 55.7988 32.125 55.8406C31.8748 55.8864 31.8085 56.0185 31.8035 56.2736C31.7947 56.8637 31.5032 57.2025 31.0527 57.1894C30.6273 57.1829 30.3107 56.8375 30.3182 56.2959C30.3182 55.9557 30.1793 55.8733 29.9065 55.7844C28.8267 55.435 28.0547 54.7377 27.7406 53.5603C27.6155 53.0854 27.8107 52.6825 28.2223 52.5464C28.3154 52.5123 28.4142 52.4989 28.5125 52.5072C28.6107 52.5155 28.7062 52.5453 28.7928 52.5946C28.8794 52.6439 28.9551 52.7117 29.015 52.7936C29.0749 52.8754 29.1178 52.9695 29.1408 53.0697C29.4686 54.5454 31.6295 54.7704 32.5868 53.9332C32.7857 53.7683 32.8721 53.4687 32.9509 53.3248Z\" fill=\"#32BF55\"\/>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:24px;\">Nag\u0142a utrata dochod\u00f3w<\/h4><div class=\"w-iconbox-text\"><p>Niespodziewana utrata pracy lub znaczny spadek dochod\u00f3w stanowi dla rodziny sytuacj\u0119 kryzysow\u0105. Zarz\u0105dzanie wydatkami domowymi w przypadku dw\u00f3ch os\u00f3b zarabiaj\u0105cych jest stresuj\u0105ce, a znalezienie odpowiedniej pomocy mo\u017ce z\u0142agodzi\u0107 obci\u0105\u017cenie rachunkami.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_eb849559\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;Rodzaje dost\u0119pnej pomocy finansowej w nag\u0142ych wypadkach&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%7D%7D&#8221;]<div class=\"wpb_text_column us_custom_eb849559\"><div class=\"wpb_wrapper\"><p>Istniej\u0105 r\u00f3\u017cne rodzaje pomocy finansowej w nag\u0142ych wypadkach, z kt\u00f3rych ka\u017cdy jest dostosowany do konkretnych potrzeb. Aby pom\u00f3c Ci okre\u015bli\u0107, kt\u00f3ra forma pomocy jest dla Ciebie najlepsza, zapoznaj si\u0119 z tymi opcjami.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_5a2ef907 height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\" style=\"--additional-gap:20px;\"><div class=\"vc_col-sm-4 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_3243c04e\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_bc739ab2 has_text_color iconpos_top style_default color_primary align_left icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><svg width=\"79\" height=\"78\" viewBox=\"0 0 79 78\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" width=\"78\" height=\"78\" rx=\"39\" fill=\"#F4F4F4\"\/>\n<g clip-path=\"url(#clip0_18272_82005)\">\n<path d=\"M19.0453 53.5133C19.0453 52.7237 19.0453 52.0289 19.0453 51.3358C19.0453 50.0411 19.5357 49.5491 20.8435 49.5147C20.9399 49.5147 21.0364 49.5017 21.1704 49.4935V28.8715C20.7738 28.8489 20.3787 28.8047 19.9869 28.7391C19.0551 28.5347 18.5614 27.9086 18.5401 26.9621C18.5401 26.6238 18.563 26.2837 18.5401 25.947C18.4208 24.5395 19.0633 23.6306 20.2828 22.9685C25.0741 20.3693 29.8442 17.7292 34.6242 15.1039L37.4032 13.582C38.7862 12.8251 40.1822 12.7973 41.5684 13.5525C47.3804 16.7359 53.1886 19.9258 58.9929 23.1222C59.9885 23.6682 60.5165 24.4888 60.4756 25.6478C60.4609 26.0451 60.4756 26.4439 60.4756 26.8428C60.4642 28.0198 59.7939 28.7342 58.6186 28.8143C58.3815 28.8306 58.1412 28.8143 57.8568 28.8143V49.5196C58.0693 49.5196 58.2998 49.5082 58.527 49.5196C59.3656 49.5687 59.9411 50.1376 59.9623 50.9762C59.9836 51.7935 59.9623 52.6027 59.9623 53.5116C60.5034 53.5116 60.9922 53.5035 61.481 53.5116C62.64 53.5345 63.2497 54.1345 63.2792 55.2853C63.2906 55.9032 63.2792 56.5211 63.2792 57.1391C63.2677 58.4043 62.6776 59.0027 61.4058 59.0043C57.3397 59.0108 53.2752 59.0108 49.2124 59.0043C48.9859 58.9896 48.7588 59.0236 48.5465 59.1039C48.3342 59.1843 48.1415 59.3092 47.9815 59.4702C45.6651 61.6705 42.8779 63.0404 39.852 63.9608C39.602 64.0243 39.3392 64.0163 39.0935 63.9379C35.9875 62.9914 33.1594 61.5479 30.7858 59.2838C30.5564 59.1098 30.2744 59.0193 29.9865 59.0272C25.9405 59.0108 21.8962 59.0174 17.8519 59.0157C16.2581 59.0157 15.7382 58.4959 15.7382 56.9069C15.7382 56.3495 15.7252 55.7921 15.7382 55.2346C15.7709 54.1508 16.3774 53.5509 17.4661 53.5214C17.9664 53.5018 18.4617 53.5133 19.0453 53.5133ZM52.3936 38.178C47.6226 37.4339 43.1583 35.359 39.5136 32.1916C37.6989 33.7669 35.6702 35.0774 33.488 36.0839C31.3115 37.0981 29.0038 37.803 26.632 38.178C26.6085 38.2475 26.5921 38.3193 26.583 38.3921C26.5258 41.8381 26.5666 45.2759 27.1878 48.6908C28.4008 55.354 32.1116 59.8887 38.5426 62.1479C39.1476 62.3864 39.8192 62.3933 40.429 62.1675C45.4493 60.3693 49.1258 57.2077 50.9256 52.0747C51.8901 49.3251 52.2759 46.4709 52.387 43.5742C52.4475 41.7907 52.3919 40.0007 52.3919 38.178H52.3936ZM39.5136 27.2662H57.4318C58.9292 27.2662 58.903 27.2662 58.9292 25.7868C58.939 25.1329 58.6905 24.716 58.1118 24.4022C52.3543 21.2504 46.6018 18.09 40.8541 14.9208C40.4508 14.6774 39.9893 14.5473 39.5183 14.5445C39.0473 14.5416 38.5842 14.666 38.178 14.9044C32.3889 18.0823 26.601 21.2597 20.814 24.4365C20.3122 24.7128 20.0261 25.0904 20.0751 25.6822C20.0948 25.9192 20.0751 26.1595 20.0751 26.3982C20.0751 27.2629 20.0751 27.2646 20.9203 27.2646L39.5136 27.2662ZM50.6052 28.865H28.3975V36.2343C28.6542 36.1689 28.8879 36.1149 29.1086 36.0512C32.705 35.0229 35.9319 33.3228 38.711 30.8037C39.3747 30.2005 39.5839 30.261 40.295 30.7907C41.7924 31.9039 43.2833 33.0417 44.8722 34.0111C46.623 35.0753 48.5601 35.7553 50.5937 36.2343L50.6052 28.865ZM56.2106 49.4984V28.8617H52.2121V36.5661C52.5881 36.6233 52.9216 36.6707 53.2551 36.7296C53.7111 36.8064 53.9694 37.0794 53.9662 37.547C53.9515 39.7555 53.9923 41.9607 53.8861 44.1708C53.8011 45.9461 53.5346 47.7133 53.3466 49.5017L56.2106 49.4984ZM25.7574 49.4984C24.9515 45.5342 24.9613 41.5962 25.0283 37.6548C25.0382 37.0794 25.2915 36.7705 25.8735 36.7165C26.1841 36.6887 26.4898 36.6135 26.7873 36.553V28.8535H22.8035V49.4984H25.7574ZM29.1282 57.4464C28.6999 56.7615 28.2929 56.1713 27.9561 55.5452C27.8888 55.3847 27.7714 55.2503 27.6215 55.1619C27.4716 55.0735 27.2971 55.036 27.1241 55.0548C24.059 55.0728 20.9955 55.063 17.9304 55.0662C17.7359 55.0662 17.543 55.0842 17.3272 55.0957V57.4513L29.1282 57.4464ZM49.8892 57.4366H61.6706V55.1169C61.6012 55.0919 61.5294 55.0738 61.4565 55.063C58.187 55.063 54.923 55.063 51.6645 55.063C51.5808 55.0645 51.4983 55.0835 51.4223 55.1187C51.3463 55.1539 51.2785 55.2045 51.2231 55.2673C50.7736 55.9604 50.3534 56.6732 49.8908 57.4317L49.8892 57.4366ZM58.3701 51.071H53.7929C52.8856 51.071 52.8872 51.071 52.6028 51.9488C52.4393 52.454 52.2661 52.9591 52.0879 53.4871H58.3668L58.3701 51.071ZM26.9066 53.4789C26.6614 52.7155 26.4571 52.0077 26.1939 51.3293C26.1432 51.1969 25.867 51.0808 25.6904 51.0775C24.6753 51.0546 23.6601 51.0661 22.6449 51.0661H20.6277V53.4789H26.9066Z\" fill=\"#32BF55\"\/>\n<path d=\"M39.5124 55.4831C37.7234 55.4837 35.9745 54.954 34.4865 53.961C32.9985 52.968 31.8382 51.5561 31.1523 49.9039C30.4665 48.2517 30.2858 46.4332 30.6331 44.6783C30.9804 42.9234 31.8401 41.3108 33.1036 40.0444C34.3671 38.7779 35.9776 37.9144 37.7317 37.563C39.4858 37.2116 41.3046 37.388 42.9585 38.07C44.6123 38.752 46.0269 39.9089 47.0234 41.3946C48.02 42.8803 48.5537 44.628 48.5573 46.4169C48.5508 48.8158 47.5965 51.1148 45.9023 52.813C44.208 54.5113 41.9112 55.471 39.5124 55.4831ZM39.7641 38.9332C35.7182 38.7272 32.1905 42.0048 31.9959 46.1505C31.8079 50.1588 35.0529 53.7192 39.0857 53.9252C40.0784 53.9751 41.0711 53.8284 42.0069 53.4935C42.9427 53.1587 43.8032 52.6422 44.5388 51.9739C45.2744 51.3055 45.8708 50.4984 46.2936 49.599C46.7164 48.6995 46.9574 47.7253 47.0027 46.7324C47.225 42.6652 43.9637 39.1473 39.7641 38.9332Z\" fill=\"#32BF55\"\/>\n<path d=\"M39.4992 24.8031C38.8401 24.8012 38.1965 24.6039 37.6495 24.2362C37.1026 23.8686 36.6769 23.3471 36.4262 22.7375C36.1756 22.128 36.1113 21.4579 36.2414 20.8118C36.3715 20.1658 36.6902 19.5728 37.1573 19.1078C37.6243 18.6428 38.2187 18.3267 38.8653 18.1995C39.5119 18.0722 40.1818 18.1395 40.7902 18.3928C41.3986 18.6461 41.9182 19.0741 42.2835 19.6227C42.6487 20.1712 42.8431 20.8158 42.8422 21.4748C42.8413 21.9129 42.7541 22.3465 42.5857 22.7509C42.4172 23.1553 42.1707 23.5225 41.8602 23.8316C41.5498 24.1406 41.1815 24.3855 40.7763 24.5522C40.3712 24.7189 39.9372 24.8042 39.4992 24.8031ZM39.4779 23.2567C39.9487 23.2607 40.4023 23.0799 40.7413 22.7532C41.0803 22.4264 41.2776 21.9798 41.2908 21.5091C41.3147 21.2613 41.2868 21.0113 41.209 20.7748C41.1312 20.5384 41.0051 20.3206 40.8388 20.1354C40.6725 19.9502 40.4695 19.8015 40.2427 19.6988C40.0159 19.5961 39.7703 19.5416 39.5214 19.5388C39.2725 19.536 39.0257 19.5848 38.7966 19.6823C38.5676 19.7798 38.3613 19.9238 38.1907 20.1052C38.0202 20.2866 37.8892 20.5014 37.8061 20.736C37.7229 20.9706 37.6893 21.22 37.7075 21.4683C37.71 21.9387 37.8968 22.3894 38.2278 22.7237C38.5587 23.0581 39.0075 23.2494 39.4779 23.2567Z\" fill=\"#32BF55\"\/>\n<path d=\"M38.4639 47.9608C39.8077 46.7495 41.0795 45.6068 42.3464 44.4609C43.0264 43.8462 43.4482 43.7678 43.8176 44.201C44.1871 44.6342 44.053 45.002 43.3926 45.597C42.0031 46.8492 40.6147 48.1025 39.2273 49.3569C38.6012 49.9225 38.3005 49.9192 37.7071 49.3307C36.9158 48.5461 36.1285 47.7576 35.3449 46.9653C34.9084 46.5239 34.8659 46.1136 35.1961 45.7605C35.5263 45.4074 36.0053 45.4499 36.445 45.8913C37.1087 46.555 37.7528 47.2285 38.4639 47.9608Z\" fill=\"#32BF55\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_18272_82005\">\n<rect width=\"47.536\" height=\"51\" fill=\"white\" transform=\"translate(15.7324 13)\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:24px;\">Pomoc rz\u0105dowa<\/h4><div class=\"w-iconbox-text\"><p>Wiele rz\u0105d\u00f3w oferuje programy kryzysowe, kt\u00f3re zapewniaj\u0105 dotacje lub niskooprocentowane po\u017cyczki osobom dotkni\u0119tym kl\u0119skami \u017cywio\u0142owymi lub trudno\u015bciami gospodarczymi. Programy te mog\u0105 by\u0107 wykorzystane na pokrycie koszt\u00f3w mieszkania i opieki medycznej. Szczeg\u00f3\u0142y r\u00f3\u017cni\u0105 si\u0119 jednak w zale\u017cno\u015bci od kraju.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_b31f667a\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_bc739ab2 has_text_color iconpos_top style_default color_primary align_left icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><svg width=\"79\" height=\"78\" viewBox=\"0 0 79 78\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" width=\"78\" height=\"78\" rx=\"39\" fill=\"#F4F4F4\"\/>\n<g clip-path=\"url(#clip0_18272_82016)\">\n<path d=\"M22.7258 40.3986C24.1062 40.2345 25.0568 40.9002 25.9126 41.8082C26.6208 42.5541 27.3764 43.2645 28.1149 43.9843C28.439 44.3085 28.8254 44.5658 29.2516 44.7413C29.6779 44.9167 30.1354 45.0068 30.5973 45.0061C31.3669 45.0111 32.1278 45.1666 32.8358 45.4637C33.5438 45.7607 34.1848 46.1934 34.7215 46.7365C36.3197 48.2879 37.9406 49.8225 39.5255 51.3497C40.3681 50.546 41.2998 49.6715 42.22 48.7783C42.9623 48.0604 43.6838 47.3239 44.4298 46.6116C45.4631 45.5958 46.8611 45.0217 48.3211 45.0136C48.818 45.0156 49.3102 44.9183 49.7678 44.7276C50.2254 44.5369 50.639 44.2568 50.9835 43.9041C51.7125 43.175 52.4737 42.4739 53.1819 41.7262C54.0113 40.8517 54.9467 40.2513 56.3063 40.4023C56.4256 39.0747 56.5449 37.7918 56.6566 36.5014C56.8459 34.2545 57.0239 32.0039 57.2455 29.7588C57.3283 28.9747 57.7135 28.2518 58.3215 27.7391C58.9296 27.2263 59.7143 26.9628 60.5138 27.0029C61.3046 27.0255 62.0558 27.3489 62.6097 27.9051C63.1637 28.4614 63.4773 29.2073 63.4848 29.9863C63.5088 36.1733 63.5088 42.3614 63.4848 48.5508C63.4848 49.8058 62.894 50.8183 62.0059 51.6909C59.2773 54.3667 56.5733 57.0686 53.8219 59.722C53.1308 60.3896 52.6971 61.0813 52.8373 62.0491C52.841 62.0956 52.841 62.1424 52.8373 62.1889C52.824 62.6831 52.5835 63.0019 52.0798 63.0057C51.5761 63.0094 51.3603 62.6887 51.3224 62.2412C51.222 60.9844 51.489 59.8842 52.4585 58.9444C55.2818 56.2295 58.0408 53.4512 60.847 50.7194C61.2245 50.3682 61.5227 49.9425 61.722 49.4703C61.9214 48.998 62.0174 48.4897 62.004 47.9784C61.9908 42.1625 62.004 36.3467 61.9737 30.5308C61.9493 29.9638 61.76 29.4156 61.4284 28.9514C61.0629 28.4405 60.4039 28.4014 59.8075 28.6139C59.5122 28.7085 59.2536 28.8902 59.0666 29.1343C58.8796 29.3785 58.7734 29.6733 58.7622 29.9789C58.535 32.5509 58.3071 35.1222 58.0787 37.693C58.0389 38.133 57.9859 38.5731 57.9575 39.0131C57.8893 40.0461 57.6999 41.0009 58.588 41.9593C59.4761 42.9177 59.2451 44.5791 58.2888 45.5506C56.0677 47.8069 53.7935 50.009 51.5383 52.2298C51.1861 52.5748 50.7808 52.6494 50.4135 52.2839C49.9874 51.8532 50.1787 51.4504 50.5612 51.0756C52.6441 49.0245 54.746 46.9734 56.81 44.8999C57.1109 44.61 57.3391 44.255 57.4765 43.8631C57.5663 43.5335 57.5433 43.184 57.4112 42.8685C57.2791 42.5531 57.0452 42.2892 56.7456 42.1178C56.44 41.9348 56.0821 41.8551 55.7263 41.8908C55.3705 41.9264 55.0362 42.0756 54.7744 42.3154C53.8907 43.1471 53.019 43.9992 52.1594 44.8719C51.6679 45.3934 51.0726 45.8095 50.4106 46.0944C49.7486 46.3793 49.0341 46.5268 48.3116 46.5277C47.767 46.5333 47.2289 46.6461 46.7291 46.8593C46.2293 47.0726 45.7779 47.3821 45.4012 47.7696C44.0284 49.1177 42.6688 50.477 41.2846 51.8121C40.9429 52.1342 40.6738 52.5234 40.4947 52.9545C40.3156 53.3856 40.2305 53.8489 40.245 54.3145C40.245 56.7591 40.245 59.2018 40.245 61.6445C40.245 61.8533 40.245 62.0622 40.2356 62.271C40.2034 62.739 39.925 63.0803 39.4782 62.9814C39.1979 62.9199 38.9498 62.5582 38.77 62.2822C38.6734 62.1311 38.7453 61.8738 38.7453 61.6631C38.7453 59.2391 38.734 56.8243 38.7453 54.4059C38.7628 53.9056 38.6713 53.4075 38.477 52.945C38.2826 52.4825 37.99 52.0663 37.6187 51.7245C36.2932 50.464 34.998 49.1718 33.7066 47.8777C33.3026 47.4523 32.8149 47.1124 32.2732 46.8787C31.7315 46.645 31.1471 46.5224 30.5557 46.5184C29.868 46.5125 29.1887 46.369 28.5592 46.0965C27.9296 45.824 27.3629 45.4283 26.8935 44.9334C26.0679 44.1018 25.2322 43.2801 24.3864 42.4683C23.612 41.7225 22.6065 41.6964 21.9248 42.3714C21.2431 43.0464 21.2791 44.0253 22.0498 44.7954C24.0967 46.8279 26.1588 48.8455 28.2114 50.8686C28.3629 51.0178 28.6015 51.1539 28.6318 51.3255C28.6867 51.6331 28.736 52.1086 28.5674 52.2447C28.3497 52.4181 27.9085 52.3641 27.5733 52.3249C27.4237 52.3063 27.2968 52.0862 27.1643 51.952C25.1445 49.963 23.1247 47.974 21.1049 45.9851C19.537 44.4393 19.5048 42.8282 20.9742 41.191C21.1111 41.0147 21.1784 40.7954 21.1636 40.5738C20.8707 37.0932 20.564 33.6181 20.2433 30.1485C20.143 29.0559 19.4859 28.4704 18.5126 28.5338C17.6018 28.5878 16.9977 29.2479 16.9977 30.3089C16.9864 36.2895 16.9864 42.2688 16.9977 48.2469C16.9977 49.2053 17.3916 49.9848 18.0846 50.6598C20.8852 53.3971 23.6479 56.1717 26.4712 58.8866C27.4389 59.819 27.7778 60.8893 27.685 62.161C27.649 62.6644 27.437 63.0411 26.8746 63.0131C26.3614 62.987 26.102 62.6402 26.1664 62.1517C26.3122 61.0627 25.7971 60.3243 25.0397 59.5971C22.3527 57.0127 19.7226 54.376 17.0527 51.7655C16.5449 51.2921 16.1441 50.7187 15.8766 50.0825C15.609 49.4464 15.4807 48.7618 15.4999 48.0735C15.5189 42.1644 15.4999 36.2553 15.4999 30.3462C15.4999 28.4032 16.7497 27.042 18.5296 26.9898C20.3096 26.9376 21.6237 28.2186 21.7847 30.1467C22.0573 33.4378 22.3527 36.7271 22.6387 40.0163C22.6614 40.1151 22.6879 40.2046 22.7258 40.3986Z\" fill=\"#32BF55\"\/>\n<path d=\"M38.7522 30.0321H32.6531C32.7212 30.8414 32.778 31.6021 32.8538 32.3611C32.9049 32.8627 32.778 33.2822 32.2251 33.3568C31.6229 33.437 31.3938 33.023 31.3389 32.5046C31.2518 31.6954 31.1799 30.8861 31.0965 30.034H26.4403C26.7603 31.3113 26.9894 32.5363 27.387 33.7111C27.8832 35.2028 28.7675 36.4969 29.7862 37.7108C29.899 37.8574 29.9785 38.0262 30.0193 38.2057C30.0602 38.3852 30.0614 38.5712 30.0229 38.7512C29.8335 39.2939 29.184 39.2733 28.7069 38.7512C27.1634 37.0711 26.0586 35.0462 25.4878 32.8515C23.0262 23.4144 30.6004 14.3354 40.4621 15.0514C46.3113 15.4766 50.5775 18.4563 52.8309 23.793C55.0842 29.1296 54.1393 34.1232 50.4336 38.6058C50.0928 39.0198 49.6914 39.3386 49.1763 38.9321C48.6613 38.5256 48.8677 38.0893 49.2388 37.6716C50.7326 36.0083 51.7519 33.9848 52.1928 31.8073C52.3064 31.2479 52.3613 30.6698 52.4522 30.0452H47.9076C47.8432 30.7649 47.7826 31.4548 47.7183 32.1466C47.6709 32.6445 47.4494 33.0323 46.8927 32.9913C46.3 32.9484 46.1352 32.5251 46.1864 31.9881C46.247 31.3672 46.2962 30.7444 46.3568 30.0601H40.2557C40.2557 30.4852 40.2406 30.916 40.2557 31.3448C40.3201 32.8011 40.0891 32.9447 39.4812 32.9895C38.9132 33.0342 38.7484 32.6333 38.7484 31.3113L38.7522 30.0321ZM38.703 28.4714V16.6028C38.4038 16.6979 38.1179 16.7129 37.9456 16.8564C37.1332 17.5128 36.2186 18.102 35.5824 18.9076C34.0846 20.7965 33.3783 23.0471 32.9939 25.3891C32.8273 26.4035 32.7534 27.4309 32.6341 28.477L38.703 28.4714ZM40.5132 16.4984L40.3239 16.7054V28.4527H46.442C46.2526 27.1027 46.1409 25.8049 45.8739 24.537C45.3418 22.0532 44.4727 19.6889 42.564 17.8801C41.9599 17.3301 41.1911 16.9571 40.5132 16.4984ZM34.6792 17.5147C30.6383 18.4843 25.9214 25.0311 26.7262 28.4677H31.1287C31.3389 24.5258 32.1513 20.7946 34.6697 17.5147H34.6792ZM47.8981 28.4527H52.3802C52.2893 23.2448 48.1083 18.6446 44.3629 17.5333C46.8434 20.7722 47.6633 24.4959 47.8981 28.4527Z\" fill=\"#32BF55\"\/>\n<path d=\"M39.5072 35.2425C40.5638 34.2039 41.7984 33.6352 43.2773 33.7694C46.1726 34.0342 48.0264 36.5907 47.375 39.3858C46.9357 41.2728 45.8279 42.7869 44.4172 44.0474C43.0766 45.2427 41.5769 46.2757 40.1529 47.3721C39.9958 47.5156 39.7932 47.6014 39.5794 47.615C39.3655 47.6286 39.1534 47.5691 38.9789 47.4467C36.6082 45.9699 34.4343 44.2861 32.8172 41.9814C31.8212 40.5549 31.2304 38.9979 31.6262 37.2489C32.3836 33.9373 36.4529 32.6432 39.066 34.8584C39.2061 34.9721 39.3425 35.0971 39.5072 35.2425ZM45.987 38.349C46.0015 37.753 45.8371 37.166 45.5145 36.6615C45.1918 36.157 44.7251 35.7574 44.173 35.5129C43.6103 35.2623 42.9831 35.188 42.3761 35.3C41.7692 35.4121 41.2119 35.7051 40.7797 36.1394C40.6316 36.2899 40.4978 36.4534 40.3801 36.628C39.706 37.6237 39.2951 37.6311 38.6418 36.6447C38.2913 36.1012 37.7723 35.6832 37.1617 35.4527C36.5512 35.2222 35.8815 35.1913 35.2517 35.3647C34.622 35.5381 34.0657 35.9065 33.6651 36.4154C33.2645 36.9244 33.0409 37.5468 33.0274 38.1905C33.0142 39.3 33.4648 40.2696 34.0935 41.1647C35.4455 43.089 37.2595 44.5211 39.2232 45.8002C39.3195 45.8434 39.4247 45.864 39.5305 45.8604C39.6363 45.8569 39.7398 45.8292 39.8329 45.7797C41.7075 44.5509 43.4515 43.1692 44.7827 41.3549C45.4379 40.4524 45.915 39.479 45.987 38.349Z\" fill=\"#32BF55\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_18272_82016\">\n<rect width=\"48\" height=\"48\" fill=\"white\" transform=\"translate(15.5 15)\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:24px;\">Organizacje non-profit<\/h4><div class=\"w-iconbox-text\"><p>Tysi\u0105ce organizacji non-profit zapewnia dora\u017an\u0105 pomoc finansow\u0105, zw\u0142aszcza w przypadku kl\u0119sk \u017cywio\u0142owych, dostaw \u017cywno\u015bci lub pomocy samotnym matkom potrzebuj\u0105cym kr\u00f3tkoterminowych \u015brodk\u00f3w finansowych. Grupy te zazwyczaj koncentruj\u0105 si\u0119 na potrzebach takich jak \u017cywno\u015b\u0107 czy mieszkanie i mog\u0105 wype\u0142ni\u0107 luki w bud\u017cecie os\u00f3b znajduj\u0105cych si\u0119 w kryzysie.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-4 wpb_column vc_column_container has_bg_color\"><div class=\"vc_column-inner us_custom_b31f667a\"><div class=\"wpb_wrapper\"><div class=\"w-iconbox us_custom_bc739ab2 has_text_color iconpos_top style_default color_primary align_left icontype_img\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;\"><svg width=\"79\" height=\"78\" viewBox=\"0 0 79 78\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n<rect x=\"0.5\" width=\"78\" height=\"78\" rx=\"39\" fill=\"#F4F4F4\"\/>\n<g clip-path=\"url(#clip0_18272_82026)\">\n<path d=\"M15.5566 47.977C15.6679 47.4798 15.7569 46.9767 15.8933 46.4863C17.5214 40.6279 24.2339 37.7964 29.5728 40.7111C29.7479 40.8078 29.923 40.9046 30.0903 41.0013C35.1206 35.8133 43.4932 35.8027 48.5603 40.6598C49.8596 39.7967 51.3395 39.243 52.8863 39.0414C57.8363 38.3459 62.8405 42.1883 63.3435 47.148C63.4741 48.4297 63.4461 49.7308 63.4306 51.0223C63.42 51.9577 62.6654 52.7277 61.7377 52.8603C61.5215 52.888 61.3036 52.9003 61.0857 52.897C58.4364 52.897 55.7865 52.897 53.1359 52.897H52.5361C52.5245 53.0595 52.51 53.194 52.5081 53.3275C52.4829 54.9662 51.444 55.9945 49.7917 55.9994C47.7032 56.0052 45.6146 55.9994 43.5261 55.9994H29.4509C27.6468 55.9994 26.7703 55.2758 26.4521 53.4842H25.9558C23.3372 53.4842 20.7185 53.4532 18.0998 53.4977C16.8626 53.519 15.991 53.0973 15.5566 51.9055V47.977ZM39.5076 54.438C42.936 54.438 46.3647 54.438 49.7937 54.438C50.6111 54.438 50.9545 54.0946 50.968 53.2772C50.9738 52.8109 50.9593 52.3446 50.9632 51.8774C50.9767 50.2416 51.0212 48.6067 50.5762 47.0048C50.1613 45.511 49.4482 44.1168 48.48 42.906C47.5117 41.6953 46.3083 40.6931 44.9423 39.9599C43.5763 39.2268 42.076 38.7778 40.5319 38.6401C38.9877 38.5023 37.4316 38.6787 35.9574 39.1585C31.464 40.6095 28.3617 44.5641 28.0763 49.2742C27.997 50.5782 28.0434 51.8861 28.0337 53.1969C28.026 54.1004 28.3617 54.44 29.269 54.4409L39.5076 54.438ZM52.5284 51.325C52.6251 51.3338 52.7035 51.3463 52.778 51.3463H56.7045C58.2165 51.3463 59.7285 51.3463 61.2395 51.3463C61.5916 51.3463 61.8993 51.266 61.8867 50.8559C61.8441 49.458 61.9583 48.0225 61.6758 46.671C60.8294 42.6178 56.9405 40.0146 52.8302 40.6066C51.6853 40.7598 50.591 41.1746 49.6321 41.8187C52.0399 45.4086 52.2063 45.9552 52.5284 51.325ZM29.0765 42.2395C28.9401 42.1496 28.8434 42.0751 28.737 42.0171C24.2629 39.5919 18.4587 42.1544 17.3559 47.1267C17.0657 48.4288 17.1625 49.8189 17.1083 51.1693C17.0812 51.8319 17.1963 51.9219 17.8648 51.9219C20.5773 51.9219 23.2894 51.9219 26.0013 51.9219C26.1522 51.9219 26.3031 51.9064 26.5362 51.8939C26.2528 48.3726 26.9 45.1068 29.0765 42.2395Z\" fill=\"#32BF55\"\/>\n<path d=\"M39.2485 36.1458C35.3413 36.1632 32.1258 33.0096 32.1016 29.1363C32.0976 28.1998 32.2785 27.2718 32.6341 26.4055C32.9898 25.5392 33.513 24.7517 34.1739 24.0883C34.8348 23.4248 35.6202 22.8984 36.4851 22.5394C37.35 22.1804 38.2773 21.9958 39.2137 21.9961C43.1402 21.9816 46.348 25.1488 46.3645 29.0579C46.3809 32.967 43.1934 36.1313 39.2485 36.1458ZM39.2301 34.598C42.3054 34.598 44.8264 32.109 44.8283 29.0744C44.8302 26.0397 42.3131 23.5546 39.234 23.5536C36.1549 23.5526 33.6339 26.0368 33.632 29.0676C33.6301 32.0983 36.1607 34.6038 39.2301 34.6029V34.598Z\" fill=\"#32BF55\"\/>\n<path d=\"M59.5224 32.3733C59.5175 35.3944 56.9995 37.8776 53.9542 37.865C50.9089 37.8524 48.3967 35.3411 48.4122 32.3346C48.4277 29.328 50.9457 26.839 53.9919 26.8477C57.0382 26.8564 59.5272 29.3348 59.5224 32.3733ZM53.9784 36.3037C56.1879 36.3037 57.991 34.5228 57.9843 32.3491C57.9775 30.1754 56.1859 28.4003 53.9678 28.4071C53.4454 28.403 52.9273 28.5022 52.4434 28.6989C51.9594 28.8956 51.5191 29.1859 51.1477 29.5533C50.7762 29.9207 50.4811 30.3578 50.2791 30.8396C50.0771 31.3214 49.9722 31.8383 49.9706 32.3607C49.9716 34.545 51.7573 36.3027 53.9784 36.3017V36.3037Z\" fill=\"#32BF55\"\/>\n<path d=\"M19.4785 32.728C19.4785 29.7001 21.9792 27.2256 25.0341 27.2266C28.089 27.2275 30.5926 29.7243 30.5887 32.7405C30.5848 35.7568 28.0639 38.2478 25.0225 38.2439C21.9811 38.24 19.4775 35.7597 19.4785 32.728ZM24.9993 36.6826C27.2242 36.6961 29.0206 34.9481 29.0303 32.7638C29.0163 31.7153 28.592 30.7141 27.8483 29.9748C27.1046 29.2356 26.1009 28.8173 25.0524 28.8095C24.0038 28.8018 22.994 29.2053 22.2395 29.9335C21.4851 30.6617 21.0461 31.6566 21.0166 32.7048C20.9866 34.8668 22.7908 36.669 24.9993 36.6826Z\" fill=\"#32BF55\"\/>\n<\/g>\n<defs>\n<clipPath id=\"clip0_18272_82026\">\n<rect width=\"47.8875\" height=\"34\" fill=\"white\" transform=\"translate(15.5566 22)\"\/>\n<\/clipPath>\n<\/defs>\n<\/svg>\n<\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:24px;\">Zasoby spo\u0142eczno\u015bciowe<\/h4><div class=\"w-iconbox-text\"><p>Poniewa\u017c <a href=\"https:\/\/whydonate.com\/peer-to-peer-fundraising\/\">kampanie peer-to-peer<\/a> opieraj\u0105 si\u0119 na zaanga\u017cowaniu wielu os\u00f3b organizuj\u0105cych mniejsze wydarzenia lub dzia\u0142ania, maj\u0105 one du\u017cy potencja\u0142 skalowalno\u015bci. W przypadku sukcesu, inicjatywy te mog\u0142yby by\u0107 powielane rok po roku.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;WhyDonate: Twoja zaufana platforma do zbi\u00f3rek funduszy w sytuacjach kryzysowych&#8221; use_theme_fonts=&#8221;yes&#8221; css=&#8221;%7B%22default%22%3A%7B%22text-align%22%3A%22center%22%7D%7D&#8221;]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image align_none\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"625\" height=\"440\" src=\"https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=9999\" class=\"attachment-large size-large\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=9999 625w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=300 300w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=600 600w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=43 43w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=284 284w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=250 250w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=142 142w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=450 450w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=64 64w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=100 100w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=350 350w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=119 119w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=60 60w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=568 568w, https:\/\/whydonate.com\/cdn-cgi\/imagedelivery\/_0vgnXOEIHPwLg2E52a7gg\/whydonate.com\/2025\/06\/Group-131.png\/w=14 14w\" sizes=\"auto, (max-width: 625px) 100vw, 625px\" title=\"\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\" class=\"attachment-large size-large wp-image-406393\"><\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-6 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><b>Jako wiod\u0105ca platforma do zbierania funduszy w Europie<\/b><br \/>\npomagamy Ci podzieli\u0107 si\u0119 swoj\u0105 histori\u0105 z odbiorcami, w\u015br\u00f3d kt\u00f3rych znajduj\u0105 si\u0119 Twoi znajomi, rodzina, a nawet nasza baza darczy\u0144c\u00f3w. Wystarczy, \u017ce uruchomisz zbi\u00f3rk\u0119.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><b>Za\u0142\u00f3\u017c zbi\u00f3rk\u0119 funduszy w nag\u0142ych wypadkach na platformie,<\/b> kt\u00f3rej mo\u017cesz zaufa\u0107. Do\u015bwiadczanie trudno\u015bci finansowych to wsp\u00f3lne ludzkie do\u015bwiadczenie i budzi empati\u0119 u wielu z nas. Okre\u015bl dok\u0142adn\u0105 kwot\u0119, kt\u00f3rej potrzebujesz i wyja\u015bnij, jak zostan\u0105 one wykorzystane.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><b>Zbierz tysi\u0105ce dolar\u00f3w jak wiele rodzin dzi\u0119ki WhyDonate:<\/b> Wiele spo\u0142eczno\u015bci zjednoczy\u0142o si\u0119, aby wesprze\u0107 osoby dotkni\u0119te kl\u0119skami \u017cywio\u0142owymi, a osoby indywidualne pomog\u0142y im stawi\u0107 czo\u0142a nag\u0142emu bezrobociu.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><b>Uzyskaj szybkie wsparcie dla swojej zbi\u00f3rki funduszy: <\/b>Oferujemy pomoc i zapoznaj si\u0119 z materia\u0142ami, kt\u00f3re pomog\u0105 Ci z \u0142atwo\u015bci\u0105 utworzy\u0107 zbi\u00f3rk\u0119 funduszy. Niezale\u017cnie od tego, czy chodzi o<a href=\"https:\/\/whydonate.com\/medical-fundraising\/\"> nag\u0142e potrzeby medyczne<\/a>, rachunki za mieszkanie, bezrobocie, czy <a href=\"https:\/\/whydonate.com\/en\/blog\/fundraising-ideas-natural-disasters\/\">pomoc w przypadku kl\u0119sk \u017cywio\u0142owych<\/a> \u2013 jeste\u015bmy do Twojej dyspozycji. Nasz zesp\u00f3\u0142 wsparcia przeprowadzi Ci\u0119 r\u00f3wnie\u017c przez proces tworzenia kampanii.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><b>Wskaz\u00f3wka dla skutecznego zbierania funduszy:<\/b> Jasny, konkretny cel, taki jak potrzeba pieni\u0119dzy na op\u0142acenie czynszu, kredytu hipotecznego, a nawet kupno tymczasowego schronienia, pozwala darczy\u0144com zobaczy\u0107, jak planujesz wykorzysta\u0107 ich darowizny. Pisz o swoich post\u0119pach co najmniej raz w tygodniu, najlepiej dodaj\u0105c zdj\u0119cia i filmy, aby darczy\u0144cy wiedzieli, \u017ce jeste\u015b odpowiedzialny, a ich darowizny maj\u0105 znaczenie dla Twojej sprawy!<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_92b2762d height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner us_custom_15f9d3f2\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;WhyDonate ma \u015bwietn\u0105 obs\u0142ug\u0119 klienta&#8221; font_container=&#8221;tag:h2|font_size:38|text_align:center|color:%23353535&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;%7B%22default%22%3A%7B%22font-weight%22%3A%22600%22%7D%7D&#8221;]<div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p style=\"text-align: center;\">Wielu klient\u00f3w wystawi\u0142o zespo\u0142owi wsparcia WhyDonate 5-gwiazdkow\u0105 opini\u0119.<br \/>\nPomog\u0105 Ci sprawi\u0107, by Twoja zbi\u00f3rka funduszy odnios\u0142a wielki sukces!<\/p>\n<\/div><\/div><div class=\"w-tabs layout_hor style_radio switch_click has_scrolling\" style=\"--sections-title-size:1em\" id=\"fundraising-eduction-tab\"><div class=\"w-tabs-list items_2 align_center\"><div class=\"w-tabs-list-h\"><button class=\"w-tabs-item active\" aria-controls=\"content-o15c\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Historie sukcesu<\/span><\/button><button class=\"w-tabs-item\" aria-controls=\"content-gd81\" aria-expanded=\"false\"><span class=\"w-tabs-item-title\">Whydonate reviews<\/span><\/button><\/div><\/div><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section active\" id=\"o15c\"><button class=\"w-tabs-section-header active\" aria-controls=\"content-o15c\" aria-expanded=\"true\"><div class=\"w-tabs-section-title\">Historie sukcesu<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o15c\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-content-carousel items_1\" id=\"education-slider\"><div class=\"owl-carousel valign_stretch dotstyle_circle navstyle_circle arrows-ver-pos_middle arrows-hor-pos_on_sides_outside arrows-disabled_hide owl-responsive-2000 with_arrows\" style=\"--items-gap:30px;--transition-duration:350ms;--arrows-size:2rem;--arrows-hor-offset:20px;--arrows-gap:10px;\" onclick=\"return {&quot;aria_labels&quot;:{&quot;prev&quot;:&quot;Poprzedni&quot;,&quot;next&quot;:&quot;Nast\\u0119pny&quot;},&quot;autoplayContinual&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplayTimeout&quot;:3000,&quot;autoWidth&quot;:false,&quot;smartSpeed&quot;:350,&quot;margin&quot;:30,&quot;mouseDrag&quot;:true,&quot;rtl&quot;:false,&quot;slideBy&quot;:&quot;1&quot;,&quot;touchDrag&quot;:true,&quot;slideTransition&quot;:&quot;&quot;,&quot;responsive&quot;:{&quot;0&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;601&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:true,&quot;stagePadding&quot;:0}}}\"><div class=\"wpb_text_column us_custom_eb849559\"><div class=\"wpb_wrapper\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-393264 aligncenter\" src=\"https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image.png\" alt=\"\" width=\"188\" height=\"188\" srcset=\"https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image.png 188w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-150x150.png 150w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-30x30.png 30w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-100x100.png 100w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-64x64.png 64w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-84x84.png 84w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-42x42.png 42w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-10x10.png 10w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-96x96.png 96w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" title=\"\"><\/p>\n<h3 style=\"text-align: center; font-weight: 600;\">Fundacja Esther Vergeer<\/h3>\n<p style=\"text-align: center;\">Zach\u0119ca dzieci i m\u0142odzie\u017c z niepe\u0142nosprawno\u015bciami do \u0107wicze\u0144. Whydonate<br \/>\npomaga im zbiera\u0107 jednorazowe i cykliczne darowizny.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-393264 aligncenter\" src=\"https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image.png\" alt=\"\" width=\"188\" height=\"188\" srcset=\"https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image.png 188w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-150x150.png 150w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-30x30.png 30w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-100x100.png 100w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-64x64.png 64w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-84x84.png 84w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-42x42.png 42w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-10x10.png 10w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-96x96.png 96w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" title=\"\"><\/p>\n<h3 style=\"text-align: center; font-weight: 600;\">Fundacja Esther Vergeer<\/h3>\n<p style=\"text-align: center;\">Zach\u0119ca dzieci i m\u0142odzie\u017c z niepe\u0142nosprawno\u015bciami do \u0107wicze\u0144. Whydonate<br \/>\npomaga im zbiera\u0107 jednorazowe i cykliczne darowizny.<\/p>\n<\/div><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-393264 aligncenter\" src=\"https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image.png\" alt=\"\" width=\"188\" height=\"188\" srcset=\"https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image.png 188w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-150x150.png 150w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-30x30.png 30w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-100x100.png 100w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-64x64.png 64w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-84x84.png 84w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-42x42.png 42w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-10x10.png 10w, https:\/\/whydonate.com\/wp-content\/uploads\/2025\/03\/Image-96x96.png 96w\" sizes=\"auto, (max-width: 188px) 100vw, 188px\" title=\"\"><\/p>\n<h3 style=\"text-align: center; font-weight: 600;\">Fundacja Esther Vergeer<\/h3>\n<p style=\"text-align: center;\">Zach\u0119ca dzieci i m\u0142odzie\u017c z niepe\u0142nosprawno\u015bciami do \u0107wicze\u0144. Whydonate<br \/>\npomaga im zbiera\u0107 jednorazowe i cykliczne darowizny.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section\" id=\"gd81\"><button class=\"w-tabs-section-header\" aria-controls=\"content-gd81\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Whydonate reviews<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-gd81\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"g-cols wpb_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-3 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-image us_custom_315afbf1 align_left\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"238\" height=\"71\" src=\"https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043.png\" class=\"attachment-us_350_0 size-us_350_0\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043.png 238w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043-101x30.png 101w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043-168x50.png 168w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043-64x19.png 64w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043-100x30.png 100w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043-141x42.png 141w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-2043-150x45.png 150w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" title=\"\"><\/div><\/div><div class=\"w-image us_custom_81f87875 align_left\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"512\" height=\"79\" src=\"https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032.png\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032.png 512w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-300x46.png 300w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-194x30.png 194w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-350x54.png 350w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-250x39.png 250w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-168x26.png 168w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-450x69.png 450w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-64x10.png 64w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-100x15.png 100w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-272x42.png 272w, https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Frame-2032-150x23.png 150w\" sizes=\"auto, (max-width: 512px) 100vw, 512px\" title=\"\"><\/div><\/div><span class=\"w-text us_custom_165571bb\"><span class=\"w-text-h\"><span class=\"w-text-value\">Rating 4.7\/5 based on 96 Reviews<\/span><\/span><\/span><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_19 icon_atright\" href=\"https:\/\/www.google.com\/maps\/place\/Whydonate:+Online+Geld+inzamelen+voor+Goed+doel+en+Particulier+-+Crowdfunding+&amp;+Fondsenwerving!\/@52.3430396,4.8292805,17z\/data=!4m18!1m9!3m8!1s0x47c5e1894bd88e31:0xe0dec4a524209684!2sWhydonate:+Online+Geld+inzamelen+voor+Goed+doel+en+Particulier+-+Crowdfunding+&amp;+Fondsenwerving*21!8m2!3d52.3430396!4d4.8292805!9m1!1b1!16s\/g\/11c6df4qbg!3m7!1s0x47c5e1894bd88e31:0xe0dec4a524209684!8m2!3d52.3430396!4d4.8292805!9m1!1b1!16s\/g\/11c6df4qbg?entry=ttu\" target=\"_blank\" rel=\"noopener\"><span class=\"w-btn-label\">View All<\/span><i class=\"fas fa-angle-right\"><\/i><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-9 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-grid us_carousel type_carousel layout_219949 hidden preload_style_spinner items_3\" id=\"us_grid_1\" style=\"--items:3;--gap:1.5rem;\"><style>.layout_219949 .w-grid-item-h{border-radius:0.6rem;box-shadow:0 0.03rem 0.06rem rgba(0,0,0,0.1),0 0.1rem 0.3rem rgba(0,0,0,0.1);transition-duration:0.3s}.layout_219949 .usg_post_content_1{text-align:left!important}.layout_219949 .usg_vwrapper_2{padding:1.5rem!important}.layout_219949 .usg_post_custom_field_3{color:#FBBD00!important;text-align:left!important;letter-spacing:3px!important}.layout_219949 .usg_post_custom_field_1{text-align:left!important}.layout_219949 .usg_post_custom_field_2{text-align:right!important}<\/style><div class=\"w-grid-list owl-carousel valign_stretch dotstyle_circle navstyle_circle arrows-ver-pos_middle arrows-hor-pos_on_sides_outside arrows-disabled_hide owl-responsive-2000 with_dots\" style=\"--transition-duration:350ms;\"><\/div><div class=\"w-grid-carousel-json hidden\" onclick='return {&quot;carousel_settings&quot;:{&quot;aria_labels&quot;:{&quot;prev&quot;:&quot;Poprzedni&quot;,&quot;next&quot;:&quot;Nast\\u0119pny&quot;},&quot;autoplayContinual&quot;:false,&quot;autoplayHoverPause&quot;:false,&quot;autoplayTimeout&quot;:3000,&quot;autoWidth&quot;:false,&quot;smartSpeed&quot;:350,&quot;margin&quot;:0,&quot;mouseDrag&quot;:true,&quot;rtl&quot;:false,&quot;slideBy&quot;:&quot;1&quot;,&quot;touchDrag&quot;:true,&quot;slideTransition&quot;:&quot;&quot;,&quot;responsive&quot;:{&quot;0&quot;:{&quot;autoHeight&quot;:false,&quot;autoplay&quot;:false,&quot;autoWidth&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:false,&quot;items&quot;:1,&quot;loop&quot;:false,&quot;nav&quot;:false,&quot;stagePadding&quot;:0,&quot;slideBy&quot;:&quot;1&quot;},&quot;601&quot;:{&quot;items&quot;:3,&quot;autoplay&quot;:false,&quot;center&quot;:false,&quot;dots&quot;:true,&quot;nav&quot;:false,&quot;autoHeight&quot;:false,&quot;autoWidth&quot;:false,&quot;loop&quot;:false,&quot;stagePadding&quot;:0}}}}'><\/div><\/div><div class=\"w-grid-none type_message\">Brak wynik\u00f3w.<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_5279a801 height_small width_full with_img\"><div class=\"l-section-img\" role=\"img\" aria-label=\"Obrazek\" data-img-width=\"1280\" data-img-height=\"351\" style=\"background-image: url(https:\/\/whydonate.com\/wp-content\/uploads\/2024\/06\/Group-1644.png);background-repeat: no-repeat;\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_middle type_default stacking_default\"><div class=\"vc_col-sm-3\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column us_custom_179b4675 has_text_color\"><div class=\"wpb_wrapper\"><h2><span style=\"color: #fff;\"><br \/>\n<span style=\"font-size: 36pt; font-weight: 600;\">Join WhyDonate&#8217;s<br \/>\nFundraising Community<\/span><\/span><\/h2>\n<\/div><\/div><div class=\"w-btn-wrapper align_none\"><a class=\"w-btn us-btn-style_1\" href=\"https:\/\/whydonate.com\/en\/account\/register\"><span class=\"w-btn-label\">Rozpocznij zbi\u00f3rk\u0119 pieni\u0119dzy<\/span><\/a><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-counter us_custom_0e0ace7d has_text_color color_text align_center has_font_size\" data-duration=\"2\"><div class=\"w-counter-value\"><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><span class=\"w-counter-value-part type_number\" data-final=\"51,340\">1<\/span><span class=\"w-counter-value-part type_text\" data-final=\"+\"><\/span><\/div><h6 class=\"w-counter-title\">Fundraisers Started<\/h6><\/div><div class=\"w-counter us_custom_70879268 has_text_color color_text align_center has_font_size\" data-duration=\"2\"><div class=\"w-counter-value\"><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><span class=\"w-counter-value-part type_number\" data-final=\"1\">1<\/span><span class=\"w-counter-value-part type_text\" data-final=\"M+\"><\/span><\/div><span class=\"w-counter-title\">Monthly Website Visitors<\/span><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-1\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-counter us_custom_0e0ace7d has_text_color color_custom align_center has_font_size\" data-duration=\"2\"><div class=\"w-counter-value\"><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><span class=\"w-counter-value-part type_number\" data-final=\"876,175\">1<\/span><span class=\"w-counter-value-part type_text\" data-final=\"+\"><\/span><\/div><h6 class=\"w-counter-title\">Active Donors<\/h6><\/div><div class=\"w-counter us_custom_70879268 has_text_color color_custom align_center has_font_size\" data-duration=\"2\"><div class=\"w-counter-value\"><span class=\"w-counter-value-part type_text\" data-final=\"\"><\/span><span class=\"w-counter-value-part type_number\" data-final=\"4.8\">1<\/span><span class=\"w-counter-value-part type_text\" data-final=\"\/5\"><\/span><\/div><h6 class=\"w-counter-title\">Average Review Rating<\/h6><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"Rozpocznij zbi\u00f3rk\u0119 funduszy w nag\u0142ych wypadkach\" font_container=\"tag:h1|font_size:40px|text_align:left|color:%23FFFFFF|line_height:47px\" use_theme_fonts=\"yes\" css=\"%7B%22default%22%3A%7B%22font-weight%22%3A%22700%22%7D%7D\"]Zbi\u00f3rki funduszy w nag\u0142ych wypadkach pomagaj\u0105 uzyska\u0107 natychmiastow\u0105 pomoc. Te zbi\u00f3rki funduszy s\u0105 przeznaczone dla os\u00f3b, kt\u00f3re borykaj\u0105 si\u0119 z nag\u0142ymi, krytycznymi problemami finansowymi. Trudne sytuacje mog\u0105 pojawi\u0107 si\u0119 w dowolnym momencie z powodu wielu nieprzewidzianych zdarze\u0144, takich jak kl\u0119ski \u017cywio\u0142owe, nag\u0142e wypadki medyczne lub nieoczekiwana...","protected":false},"author":70,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-413961","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/pages\/413961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/users\/70"}],"replies":[{"embeddable":true,"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/comments?post=413961"}],"version-history":[{"count":9,"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/pages\/413961\/revisions"}],"predecessor-version":[{"id":418095,"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/pages\/413961\/revisions\/418095"}],"wp:attachment":[{"href":"https:\/\/whydonate.com\/pl\/wp-json\/wp\/v2\/media?parent=413961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}